{"id":89987,"date":"2024-08-28T09:12:46","date_gmt":"2024-08-28T12:12:46","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=89987"},"modified":"2024-08-28T17:14:40","modified_gmt":"2024-08-28T20:14:40","slug":"francisco-que-o-senhor-conceda-o-dom-da-paz-aos-muitos-paises-em-guerra","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/francisco-que-o-senhor-conceda-o-dom-da-paz-aos-muitos-paises-em-guerra\/","title":{"rendered":"Francisco: que o Senhor conceda o dom da paz aos muitos pa\u00edses em guerra"},"content":{"rendered":"<figure class=\"article__image\" style=\"text-align: justify;\"><span class=\"didascalia_img\">Papa Francisco durante a Audi\u00eancia Geral\u00a0 (VATICAN MEDIA Divisione Foto)<\/span><\/figure>\n<div class=\"article__meta audioInside\" data-mediatype=\"\">\n<div class=\"article__subTitle\" style=\"text-align: justify;\">Ao t\u00e9rmino da Audi\u00eancia Geral, um novo apelo do Papa pela Palestina, Israel, a \u201cmartirizada Ucr\u00e2nia\u201d, Mianmar e o Kivu do Norte: &#8220;rezemos para que os mares e desertos se tornem espa\u00e7os onde Deus possa abrir caminhos de liberdade e fraternidade.&#8221;<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text\">\n<p style=\"text-align: justify;\"><b>Vatican News<\/b><\/p>\n<p style=\"text-align: justify;\">O pensamento do Papa Francisco voltou mais uma vez aos pa\u00edses dilacerados por conflitos e viol\u00eancias ao t\u00e9rmino da Audi\u00eancia Geral desta quarta-feira, 28 de agosto. O Pont\u00edfice, expressou sua preocupa\u00e7\u00e3o com as popula\u00e7\u00f5es que est\u00e3o sofrendo, em meio a grandes dificuldades e dores:<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--border embed_style\">\n<blockquote><p>\u201cPensemos nos pa\u00edses em guerra, tantos pa\u00edses em guerra. Pensemos na Palestina, em Israel, na martirizada Ucr\u00e2nia, pensemos em Mianmar, no Kivu do Norte.\u201d<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">\u201cTantos pa\u00edses em guerra\u201d, repetiu o Papa, invocando a Deus para que as hostilidades e os confrontos cessem.<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"article__innerTitle\">Ou\u00e7a com a voz do Papa e compartilhe<\/div>\n<\/div>\n<div>\n<audio class=\"wp-audio-shortcode\" id=\"audio-89987-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2024\/08\/28\/11\/138240264_F138240264.mp3?_=1\" \/><a href=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2024\/08\/28\/11\/138240264_F138240264.mp3\">https:\/\/media.vaticannews.va\/media\/audio\/s1\/2024\/08\/28\/11\/138240264_F138240264.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<h2 style=\"text-align: justify;\">Que o Senhor lhes conceda o dom da paz<\/h2>\n<p style=\"text-align: justify;\">Francisco lembra da Ucr\u00e2nia tamb\u00e9m na sua sauda\u00e7\u00e3o aos fi\u00e9is poloneses, que h\u00e1 alguns anos t\u00eam demonstrado \u201cgrande ajuda samaritana e grande compreens\u00e3o para com os refugiados de guerra\u201d, e os exorta a continuar suas obras de bem.<\/p>\n<p style=\"text-align: justify;\"><i>&#8220;Continuem a ser hospitaleiros com aqueles que perderam tudo e v\u00eam at\u00e9 voc\u00eas, contando com a sua miseric\u00f3rdia e com o seu aux\u00edlio fraterno. Que a Sagrada Fam\u00edlia de Nazar\u00e9, que tamb\u00e9m, em um momento de perigo, procurou ref\u00fagio em um pa\u00eds estrangeiro, os sustente nisso.&#8221;<\/i><\/p>\n<h2 style=\"text-align: justify;\">Intercess\u00e3o de Santo Agostinho<\/h2>\n<p style=\"text-align: justify;\">E no dia em que se celebra a mem\u00f3ria lit\u00fargica de Santo Agostinho, aos peregrinos de l\u00edngua francesa, o Papa tamb\u00e9m convida a invoc\u00e1-lo para que inspire solidariedade entre os povos.<\/p>\n<p style=\"text-align: justify;\"><i>&#8220;Rezemos a Santo Agostinho, que hoje celebramos, para que os mares e desertos se tornem espa\u00e7os onde Deus possa abrir caminhos de liberdade e fraternidade.&#8221;<\/i><\/p>\n<h2 style=\"text-align: justify;\">Buscar a sabedoria e Deus como o bispo de Hipona<\/h2>\n<p style=\"text-align: justify;\">Dirigindo-se, ent\u00e3o, aos alem\u00e3es, Francisco relembra a \u201clonga jornada interior de busca\u201d de Agostinho, bispo de Hipona, que o levou a perceber o quanto Deus \u201cnos ama e que nossos cora\u00e7\u00f5es inquietos encontram descanso e paz somente Nele\u201d, desejando \u201cessa experi\u00eancia da paz de Deus, que supera todo entendimento\u201d.<\/p>\n<p style=\"text-align: justify;\">Por fim, antes da b\u00ean\u00e7\u00e3o final, o Papa convidou todos a imitar Santo Agostinho, a serem \u201csedentos da verdadeira sabedoria\u201d e a buscar \u201cincessantemente o Senhor, fonte viva do amor eterno\u201d.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Papa Francisco durante a Audi\u00eancia Geral\u00a0 (VATICAN MEDIA Divisione Foto) Ao t\u00e9rmino da Audi\u00eancia Geral, um novo apelo do Papa pela Palestina, Israel, a \u201cmartirizada Ucr\u00e2nia\u201d, Mianmar e o Kivu do Norte: &#8220;rezemos para que os mares e desertos se tornem espa\u00e7os onde Deus possa abrir caminhos de liberdade e fraternidade.&#8221; Vatican News O pensamento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89988,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-89987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/89987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=89987"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/89987\/revisions"}],"predecessor-version":[{"id":89990,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/89987\/revisions\/89990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/89988"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=89987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=89987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=89987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}