{"id":88993,"date":"2024-06-22T09:06:29","date_gmt":"2024-06-22T12:06:29","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=88993"},"modified":"2024-06-24T15:08:01","modified_gmt":"2024-06-24T18:08:01","slug":"deus-nao-abandona-seus-filhos","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/deus-nao-abandona-seus-filhos\/","title":{"rendered":"Deus n\u00e3o abandona seus filhos!"},"content":{"rendered":"<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">Vivenciando a celebra\u00e7\u00e3o do 12\u00ba. Domingo do Tempo Comum nos deparamos que a vida pode ter momentos assustadores, momentos de inquieta\u00e7\u00e3o e de crise em que perdemos o p\u00e9 e sentimos que nos afundamos. Onde est\u00e1 Deus, nesses momentos? Ele \u201cimporta-se\u201d conosco? A liturgia deste 12.\u00ba domingo comum garante-nos: Deus n\u00e3o abandona nem ignora os filhos e filhas que criou; Ele ampara-os com amor fiel, vigilante e criador. Ele vai sempre ao nosso lado, cuidando de n\u00f3s, em cada passo da viagem da vida. Por isso a liturgia nos convida a aprofundarmos o sentido da f\u00e9 que resiste \u00e0 tenta\u00e7\u00e3o. Cristo nos encoraja a vencermos a falta de f\u00e9 e a confiar em sua Palavra, para que as tormentas da vida n\u00e3o nos afastem do caminho.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">Na\u00a0<strong><span style=\"font-weight: normal;\">primeira leitura\u00a0<\/span><\/strong>\u2013 J\u00f3 38,1.8-11 \u2013 Deus revela-se a um crente chamado J\u00f3 como o Senhor que domina o mar e conhece os segredos do universo e da vida. Nada na cria\u00e7\u00e3o lhe \u00e9 indiferente: Ele cuida de todos os seres criados com amor de pai e de m\u00e3e. Ao homem resta entregar-se nas m\u00e3os desse Deus omnipotente e cheio de amor, com humildade e com total confian\u00e7a. A primeira leitura \u00e9 uma manifesta\u00e7\u00e3o de Deus a J\u00f3 no meio da tempestade. Este ainda n\u00e3o consegue compreender as interpreta\u00e7\u00f5es do Senhor. Este texto nos prepara para compreendermos o Evangelho que em seu vers\u00edculo final, revela a inten\u00e7\u00e3o de todo relato: \u201cquem \u00e9 este, a quem at\u00e9 o vento e o mar obedecem? (Mc 4,41).<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">No\u00a0<strong><span style=\"font-weight: normal;\">Evangelho \u2013 Mc 4,35-41<\/span> \u2013<\/strong>, Marcos prop\u00f5e-nos uma catequese sobre a presen\u00e7a tranquilizadora e pacificadora de Jesus na viagem que a Igreja e os disc\u00edpulos v\u00e3o fazendo pela hist\u00f3ria. Com Jesus no barco, os disc\u00edpulos estar\u00e3o sempre aptos a enfrentar todo o tipo de tempestades; com Jesus no comando, eles sabem que a meta final da viagem n\u00e3o pode deixar de ser o porto seguro onde os espera a Vida verdadeira. Jesus e aquele que exerce, sobre o vento e o mar, seu poder-autoridade. Os disc\u00edpulos est\u00e3o em constante processo de reconhecimento e de convers\u00e3o a Deus, buscando ver em Jesus o Enviado do Pai. Eles haviam escutado do Senhor, anteriormente, v\u00e1rias par\u00e1bolas sobre o Reino. A cena de hoje situa-se logo ap\u00f3s esses ensinamentos. Diante da fragilidade da barca, da forte chuva e a ventania, eles acordam a Jesus com medo e tremor. O Senhor acalma toda a realidade e questiona-os: \u201cainda n\u00e3o tendes f\u00e9?\u201d (Cf. Mc 4,40b). Ainda n\u00e3o conseguem assimilar o que ouviram na pr\u00e1tica de vida?<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">A\u00a0<strong><span style=\"font-weight: normal;\">segunda leitura \u2013 2Cor 5,14-17 \u2013 S\u00e3o<\/span><\/strong><b>\u00a0<\/b>Paulo convida-nos a olhar para a Cruz e a contemplar o amor de Jesus expresso na entrega total da sua vida ao projeto do Pai em favor dos homens. Deus enviou o seu Filho para caminhar conosco e nos ensinar a viver no amor. \u00c9 precisamente isso que move Paulo no seu apostolado: ele considera que a sua miss\u00e3o \u00e9 dar testemunho desse amor, a fim de que todos os que escutam a Boa nova de Jesus possam viver como pessoas novas, libertas do ego\u00edsmo que escraviza e mata. Se estamos em Cristo, somos uma nova criatura! O autor faz um forte apelo \u00e0 solidariedade: Cristo conosco, e n\u00f3s com ele e com os irm\u00e3os e irm\u00e3s. Estar com Cristo significa ser uma nova criatura que vive em comunh\u00e3o.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">Jesus continua acalmando as tempestades. O sono tranquilo de Jesus revela a confian\u00e7a em Deus. Pode indicar que Jesus est\u00e1 pondo nos disc\u00edpulos \u00e0 prova: eles precisam come\u00e7ar a caminhar sozinhos, assumindo os compromissos do Mestre sem a presen\u00e7a f\u00edsica dele. Apesar dos perigos, precisam passar para a \u201coutra margem\u201d e enfrentar novos desafios. Ainda que Jesus n\u00e3o esteja fisicamente presente, quando temos f\u00e9 no Ressuscitado, o mar se acalma e o medo desaparece. A falta de f\u00e9 provoca o medo que paralisa, que n\u00e3o deixa avan\u00e7ar e alcan\u00e7ar novos horizontes. Muitas vezes somos como pequeninas barcas agitadas pelas ondas e amea\u00e7adas de afundar ao des\u00e2nimo. As etapas dif\u00edceis da vida pelas quais passamos \u2013 doen\u00e7as, viol\u00eancia, desemprego, perdas pessoais, falta de sentido \u2013 tendem a deixar-nos paralisados, sem a\u00e7\u00e3o. \u00c9 ent\u00e3o que mais somos chamados a invocar \u201caquele a quem at\u00e9 o vento e o mar obedecem\u201d.<\/p>\n<p style=\"text-align: justify; text-indent: 35.4pt; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\">Para voc\u00ea: quem \u00e9 Jesus. Jesus acalma as tempestades e n\u00e3o abandona seus filhos!<\/p>\n<p style=\"text-align: center; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\" align=\"center\"><b>+ Anuar Battisti<\/b><\/p>\n<p style=\"text-align: center; background: white; vertical-align: baseline; margin: 0cm 0cm 18.0pt 0cm;\" align=\"center\"><b>Arcebispo Em\u00e9rito de Maring\u00e1, PR<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivenciando a celebra\u00e7\u00e3o do 12\u00ba. Domingo do Tempo Comum nos deparamos que a vida pode ter momentos assustadores, momentos de inquieta\u00e7\u00e3o e de crise em que perdemos o p\u00e9 e sentimos que nos afundamos. Onde est\u00e1 Deus, nesses momentos? Ele \u201cimporta-se\u201d conosco? A liturgia deste 12.\u00ba domingo comum garante-nos: Deus n\u00e3o abandona nem ignora os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-88993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/88993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=88993"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/88993\/revisions"}],"predecessor-version":[{"id":88995,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/88993\/revisions\/88995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/55814"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=88993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=88993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=88993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}