{"id":87734,"date":"2024-03-25T10:39:26","date_gmt":"2024-03-25T13:39:26","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=87734"},"modified":"2024-03-25T15:42:10","modified_gmt":"2024-03-25T18:42:10","slug":"bispos-catolicos-do-haiti-pedem-o-fim-da-violencia-e-a-reconciliacao-nacional","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/bispos-catolicos-do-haiti-pedem-o-fim-da-violencia-e-a-reconciliacao-nacional\/","title":{"rendered":"Bispos cat\u00f3licos do Haiti pedem o fim da viol\u00eancia e a reconcilia\u00e7\u00e3o nacional"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Mulher reza em frente \u00e0 Catedral, Haiti.\u00a0<\/em><em>Cr\u00e9dito: Divulga\u00e7\u00e3o ACN<\/em><\/p>\n<p style=\"text-align: center;\"><strong><em>Carta enviada \u00e0 Ajuda \u00e0 Igreja que Sofre \u2013 ACN, assinada por todos os 10 bispos cat\u00f3licos do pa\u00eds, refor\u00e7a o apelo do Papa Francisco para que as ora\u00e7\u00f5es ao povo haitiano sejam ouvidas na terra e no c\u00e9u, confiando na miseric\u00f3rdia de Deus e na sua compaix\u00e3o pelos seus filhos<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Os bispos cat\u00f3licos do Haiti expressaram profunda preocupa\u00e7\u00e3o com a viol\u00eancia que est\u00e1 varrendo o pa\u00eds. Em carta enviada na \u00faltima semana \u00e0 ACN \u2013 Ajuda \u00e0 Igreja que Sofre, assinada por todos os 10 bispos cat\u00f3licos do pa\u00eds e que pede o fim de toda a viol\u00eancia e a reconcilia\u00e7\u00e3o nacional, ecoando um apelo recente do Papa Francisco.<\/p>\n<p style=\"text-align: justify;\">Em sua mensagem, os bispos encorajam todas as ag\u00eancias e atores nacionais a encontrar uma solu\u00e7\u00e3o para a crise atual e restaurar a paz e a seguran\u00e7a para todos os haitianos. Pedem tamb\u00e9m o estabelecimento de um governo de transi\u00e7\u00e3o inclusivo, capaz de garantir a verdadeira harmonia nacional.<\/p>\n<p style=\"text-align: justify;\">A carta explica que, para manter sua neutralidade, a Confer\u00eancia Episcopal Haitiana n\u00e3o nomear\u00e1 ningu\u00e9m para representar a Igreja Cat\u00f3lica no Conselho Presidencial ou em qualquer outra estrutura de governo. No entanto, manifesta a sua esperan\u00e7a de que o di\u00e1logo em curso conduza a um acordo inclusivo, patri\u00f3tico e duradouro, no melhor interesse de todo o povo haitiano.<\/p>\n<p style=\"text-align: justify;\">Os bispos enfatizam que todos os setores da sociedade haitiana devem apoiar o sonho de um pa\u00eds sem viol\u00eancia: &#8220;Vamos acabar com esses atos violentos que causam tanto sofrimento, porque a viol\u00eancia gera viol\u00eancia, o \u00f3dio gera mais \u00f3dio e a morte gera mais mortos&#8221;, diz o comunicado. Os bispos tamb\u00e9m mencionam o convite do Papa Francisco, feito durante a ora\u00e7\u00e3o do Angelus, no domingo, 10 de mar\u00e7o, para rezar pelo fim de todas as formas de viol\u00eancia no Haiti: &#8220;Cada morte violenta cometida contra outro ser humano \u00e9 uma ferida na carne da humanidade; cada morte violenta nos diminui como pessoas&#8221;.<\/p>\n<p style=\"text-align: justify;\">A situa\u00e7\u00e3o humanit\u00e1ria no Haiti tornou-se extremamente grave nas \u00faltimas semanas, devido \u00e0 crise pol\u00edtica e social que tomou conta do pa\u00eds desde o assassinato do Presidente, em julho de 2021. De acordo com dados fornecidos pela Confer\u00eancia Episcopal da Am\u00e9rica Latina (CELAM) e pela Confedera\u00e7\u00e3o Latino-Americana dos Religiosos (CLAR), mais de tr\u00eas milh\u00f5es de crian\u00e7as precisam de ajuda humanit\u00e1ria, 362.000 pessoas est\u00e3o deslocadas internamente e metade da popula\u00e7\u00e3o vive na pobreza, com uma expectativa de vida de apenas 64 anos.<\/p>\n<p style=\"text-align: justify;\">Por causa da viol\u00eancia, muitas pessoas perderam seus entes queridos, as mulheres frequentemente t\u00eam seus direitos fundamentais violados e muitos haitianos n\u00e3o t\u00eam as condi\u00e7\u00f5es m\u00ednimas para uma vida digna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mulher reza em frente \u00e0 Catedral, Haiti.\u00a0Cr\u00e9dito: Divulga\u00e7\u00e3o ACN Carta enviada \u00e0 Ajuda \u00e0 Igreja que Sofre \u2013 ACN, assinada por todos os 10 bispos cat\u00f3licos do pa\u00eds, refor\u00e7a o apelo do Papa Francisco para que as ora\u00e7\u00f5es ao povo haitiano sejam ouvidas na terra e no c\u00e9u, confiando na miseric\u00f3rdia de Deus e na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67995,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-87734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-featured"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/87734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=87734"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/87734\/revisions"}],"predecessor-version":[{"id":87736,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/87734\/revisions\/87736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/67995"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=87734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=87734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=87734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}