{"id":86830,"date":"2024-02-01T09:33:38","date_gmt":"2024-02-01T12:33:38","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=86830"},"modified":"2024-02-01T14:35:21","modified_gmt":"2024-02-01T17:35:21","slug":"venca-a-procrastinacao-com-estes-passos-simples","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/venca-a-procrastinacao-com-estes-passos-simples\/","title":{"rendered":"Ven\u00e7a a procrastina\u00e7\u00e3o com estes passos simples"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"subtitle\"><span>Amanh\u00e3 eu come\u00e7o, ainda n\u00e3o estou pronto, estou com pregui\u00e7a, ainda tenho tempo&#8230; Voc\u00ea provavelmente j\u00e1 disse essas frases para si mesmo ou j\u00e1 ouviu quando as pessoas falam sobre procrastina\u00e7\u00e3o.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Aprocrastina\u00e7\u00e3o pode ocorrer nas atividades cotidianas, no trabalho, na escola, bem como na vida espiritual.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Cais de A\u00e7o\" href=\"https:\/\/twitter.com\/pierssteel?lang=en\" target=\"_blank\" rel=\"noopener\"><span>Piers Steel<\/span><\/a><span>\u00a0, autor e pesquisador do assunto, deduziu o seguinte:<\/span><\/p>\n<blockquote class=\"wp-block-aleteia-blockquote\"><p><span>A procrastina\u00e7\u00e3o \u00e9 a tend\u00eancia de adiar ou atrasar a conclus\u00e3o de uma tarefa, evitando responsabilidades, decis\u00f5es e tarefas que precisam ser realizadas. \u201cCom o objetivo de desenvolver outras coisas, exceto o seu objetivo principal\u201d<\/span><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><span>Geralmente, ap\u00f3s adiar uma atividade, projeto ou tarefa, surge o sentimento de culpa por n\u00e3o ter aproveitado o tempo necess\u00e1rio para fazer o que hav\u00edamos planejado na hora certa, deixando as coisas para \u00faltima hora, dando lugar ao estresse.\u00a0<\/span><\/p>\n<div class=\"block-image-copyrigth-wrap\" style=\"text-align: justify;\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-796357\" src=\"https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?w=1024\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg 1200w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=150,100 150w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=300,200 300w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=1024,683 1024w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=620,413 620w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=360,240 360w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=1140,760 1140w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=375,250 375w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=630,420 630w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2024\/01\/shutterstock_1816833623.jpg?resize=266,177 266w\" alt=\"procratina\u00e7\u00e3o\" width=\"1200\" height=\"800\" \/><\/figure>\n<div class=\"copyright-text\"><span>Nova \u00c1frica | Obturador<\/span><\/div>\n<\/div>\n<div class=\"wp-block-aleteia-heading3\" style=\"text-align: justify;\">\n<h2><span>Uma anedota nos Jogos Ol\u00edmpicos de Atlanta em 1996<\/span><\/h2>\n<\/div>\n<blockquote class=\"wp-block-quote\"><p><span>Contaremos uma hist\u00f3ria baseada em um caso real que explica o impacto que a procrastina\u00e7\u00e3o pode ter em nossas vidas.\u00a0<\/span><\/p>\n<div id=\"aleteia-welcome\"><\/div>\n<p><span>Os principais favoritos para vencer este teste foram Gary Hall Jr. (americano) e Alexander Popov (russo). Como era de se esperar, um deles obteve a medalha de ouro e o outro a medalha de prata.<\/span><\/p>\n<p><span>Gary Hall Jr., jovem atleta americano, 20 anos. Desde pequeno possu\u00eda habilidades inatas de nata\u00e7\u00e3o segundo seus primeiros treinadores, que foram fortalecidas com os treinos na piscina. Por\u00e9m, segundo os cronistas, nos \u00faltimos dois anos de prepara\u00e7\u00e3o para as Olimp\u00edadas, Gary Hall Jr. faltou treinador porque parava de treinar com muita facilidade, n\u00e3o dedicava tempo suficiente a isso e as pessoas ao seu redor acabavam ficando desesperadas devido a suas atitudes indisciplinadas do atleta. Ele veio para as Olimp\u00edadas acompanhado de confian\u00e7a, de sua habilidade inata para nadar e de seu pai, que era um ex-nadador profissional.<\/span><\/p>\n<p><span>Alexander Popov era um jovem atleta russo de 20 anos. Este nadador foi se tornando aos poucos. Embora n\u00e3o tivesse habilidades inatas para nadar, os cronistas referiam-se a ele como uma pessoa constante, ordeira e disciplinada.<\/span><\/p>\n<p><span>Certamente teve apoio, contato em competi\u00e7\u00f5es internacionais e treinadores altamente capacitados; Ele entendeu que precisava treinar para atingir 100%, pensando nas Olimp\u00edadas que estavam por vir. Ele tinha certeza de que praticar para aperfei\u00e7oar a nata\u00e7\u00e3o era muito importante para ser o melhor em sua especialidade.\u00a0<\/span><\/p>\n<p><span>A medalha foi conquistada por Popov.<\/span><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><span>Piers Steel acredita que tanto esta como todas as hist\u00f3rias de procrastina\u00e7\u00e3o que conhecemos \u2013 ou que podemos criar diariamente \u2013 se resumem na\u00a0<\/span><strong><span>falta de motiva\u00e7\u00e3o, uma ideia decomposta numa f\u00f3rmula cujo resultado determinar\u00e1 o sucesso ou o fracasso na concretiza\u00e7\u00e3o da tarefa. planejado.<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span>Por isso deixamos algumas dicas que voc\u00ea pode usar para vencer a batalha contra a procrastina\u00e7\u00e3o:\u00a0<\/span><\/p>\n<h2 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong><span>1 MINIMIZE QUAISQUER DISTRA\u00c7\u00d5ES<\/span><\/strong><\/h2>\n<div class=\"block-image-copyrigth-wrap\" style=\"text-align: justify;\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-783841\" src=\"https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?w=1024\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" srcset=\"https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg 1200w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=150,100 150w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=300,200 300w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=1024,683 1024w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=620,413 620w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=360,240 360w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=1140,760 1140w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=375,250 375w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=630,420 630w, https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2023\/11\/shutterstock_2026891535.jpg?resize=266,177 266w\" alt=\"desligar o smartphone\" width=\"1200\" height=\"800\" \/><\/figure>\n<div class=\"copyright-text\"><span>Ton Fot\u00f3grafo 4289 | Obturador<\/span><\/div>\n<\/div>\n<p style=\"text-align: justify;\"><span>Desligue as notifica\u00e7\u00f5es do celular, ou\u00e7a m\u00fasicas relaxantes, encontre um espa\u00e7o tranquilo e confort\u00e1vel para fazer as coisas. N\u00e3o trabalhe na cama, pois segundo especialistas o c\u00e9rebro associa que a cama \u00e9 para dormir, ent\u00e3o se voc\u00ea trabalhar l\u00e1 vai ficar com sono e vai acabar exausto e vai procrastinar novamente.\u00a0<\/span><\/p>\n<h2 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong><span>2 GERENCIE SEU TEMPO<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\"><span>Voc\u00ea pode designar um hor\u00e1rio espec\u00edfico para a realiza\u00e7\u00e3o daquela atividade ou atividades, manter a ordem \u00e9 sempre bom. Al\u00e9m de implementar t\u00e9cnicas que te levem ao seu objetivo de forma saud\u00e1vel, como por exemplo: a t\u00e9cnica Pomodoro.\u00a0<\/span><\/p>\n<div class=\"wp-block-aleteia-read-also read-also\" style=\"text-align: justify;\" data-category=\"Estilo de vida\" data-category-english=\"lifestyle\">\n<figure><img decoding=\"async\" src=\"https:\/\/wp.es.aleteia.org\/wp-content\/uploads\/sites\/7\/2022\/04\/shutterstock_1690555750.jpg?w=300&amp;h=169&amp;crop=1\" alt=\"PASSOS\" \/><\/figure>\n<div class=\"read-also-inner\"><em><span>Voc\u00ea pode estar interessado:<\/span><\/em><a href=\"https:\/\/es.aleteia.org\/2022\/04\/19\/pasos-para-alcanzar-sus-objetivos\/\" target=\"_self\" rel=\"noopener\"><span>Passos para atingir seus objetivos<\/span><\/a><\/div>\n<\/div>\n<h2 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong><span>3 ESTABELE\u00c7A PRIORIDADES<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\"><span>Fa\u00e7a uma lista das coisas mais urgentes, do que pode esperar \u2013 mas \u00e9 importante fazer \u2013, do que voc\u00ea pode delegar e do que pode fazer a tempo. Dessa forma, voc\u00ea far\u00e1 as coisas uma por uma para atingir seus objetivos.<\/span><\/p>\n<h2 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong><span>4 N\u00c3O D\u00ca DESCULPAS E ESTABELE\u00c7A PRAZOS\u00a0<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\"><span>Isso o ajudar\u00e1 a saber que existe um prazo e a se livrar de todas as desculpas que o impedem de seguir em frente, fazendo com que voc\u00ea caia em uma atitude perfeccionista e deixe de fazer as coisas por n\u00e3o se considerar bom o suficiente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Relembre a hist\u00f3ria dos jovens atletas: n\u00e3o basta ter talento, \u00e9 preciso coloc\u00e1-lo em pr\u00e1tica para nos exercitarmos e alcan\u00e7armos nossos objetivos, em qualquer \u00e1rea da vida.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amanh\u00e3 eu come\u00e7o, ainda n\u00e3o estou pronto, estou com pregui\u00e7a, ainda tenho tempo&#8230; Voc\u00ea provavelmente j\u00e1 disse essas frases para si mesmo ou j\u00e1 ouviu quando as pessoas falam sobre procrastina\u00e7\u00e3o. Aprocrastina\u00e7\u00e3o pode ocorrer nas atividades cotidianas, no trabalho, na escola, bem como na vida espiritual.\u00a0 Piers Steel\u00a0, autor e pesquisador do assunto, deduziu o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":86831,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-86830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/86830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=86830"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/86830\/revisions"}],"predecessor-version":[{"id":86833,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/86830\/revisions\/86833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/86831"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=86830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=86830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=86830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}