{"id":75989,"date":"2022-09-16T09:38:50","date_gmt":"2022-09-16T12:38:50","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=75989"},"modified":"2022-09-16T12:40:40","modified_gmt":"2022-09-16T15:40:40","slug":"direto-do-vaticano-papa-incitar-ao-odio-nada-tem-a-ver-com-o-espirito-religioso","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/direto-do-vaticano-papa-incitar-ao-odio-nada-tem-a-ver-com-o-espirito-religioso\/","title":{"rendered":"Direto do Vaticano \u2013 Papa: incitar ao \u00f3dio nada tem a ver com o esp\u00edrito religioso"},"content":{"rendered":"<h2 class=\"subtitle\" style=\"text-align: justify;\">Boletim Direto do Vaticano de 16 de setembro de 2022<\/h2>\n<ol style=\"text-align: justify;\">\n<li>Nem \u201cadministradores do sagrado\u201d nem \u201cpol\u00edcias\u201d: a mensagem do Papa aos l\u00edderes cat\u00f3licos no Cazaquist\u00e3o<\/li>\n<li>\u201cS\u00f3 servindo \u00e0 paz \u00e9 que o teu nome ficar\u00e1 na hist\u00f3ria\u201d, diz Francisco aos l\u00edderes mundiais<\/li>\n<li>Do Cazaquist\u00e3o, D. Schneider adverte o Papa sobre os riscos do di\u00e1logo inter-religioso<\/li>\n<\/ol>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h3 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong>1 NEM \u201cADMINISTRADORES DO SAGRADO\u201d NEM \u201cPOL\u00cdCIAS\u201d: A MENSAGEM DO PAPA AOS L\u00cdDERES CAT\u00d3LICOS NO CAZAQUIST\u00c3O<\/strong><\/h3>\n<p style=\"text-align: justify;\">Por Camille Dalmas, Cazaquist\u00e3o: Os cl\u00e9rigos n\u00e3o s\u00e3o \u201cadministradores do sagrado ou pol\u00edcias preocupados em fazer respeitar as normas religiosas\u201d, o Papa Francisco advertiu durante um encontro com cat\u00f3licos cazaques na Catedral da M\u00e3e de Deus do Perp\u00e9tuo Socorro, em Nur-Sultan, a 15 de Setembro. Instou os membros da Igreja Cat\u00f3lica a serem, atrav\u00e9s da sua proximidade com o povo, \u201c\u00edcones vivos do cora\u00e7\u00e3o compassivo de Cristo\u201d.<\/p>\n<p style=\"text-align: justify;\">Na pequena catedral da capital, o pont\u00edfice foi recebido pelos bispos, padres, di\u00e1conos, pessoas consagradas e leigos do pa\u00eds. Ap\u00f3s um tempo de ora\u00e7\u00e3o, representantes de cada uma destas realidades eclesiais falaram das suas vidas como crist\u00e3os no Cazaquist\u00e3o, onde a Igreja Cat\u00f3lica representa menos de 1% da popula\u00e7\u00e3o de acordo com a Santa S\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>A Igreja, uma elite religiosa<\/strong><\/p>\n<p style=\"text-align: justify;\">Como \u00e9 frequentemente o caso em pa\u00edses onde o catolicismo \u00e9 uma minoria, o Papa salientou a \u201cgra\u00e7a oculta\u201d de ser uma \u201cpequena Igreja, um pequeno rebanho\u201d. Em tal situa\u00e7\u00e3o, os cat\u00f3licos podem descobrir que n\u00e3o s\u00e3o \u201cauto-suficientes\u201d e acompanhar humildemente as pessoas, \u201cem vez de mostrar [as suas] for\u00e7as, [os seus] n\u00fameros, [as suas] estruturas\u201d.<\/p>\n<p style=\"text-align: justify;\">Referindo-se \u00e0 diversidade da Igreja Cazaque \u2013 polacos, alem\u00e3es, cazaques convertidos, mission\u00e1rios de todo o mundo \u2013 o Papa salientou como a beleza da Igreja reside no fato de ser uma fam\u00edlia \u201cna qual ningu\u00e9m \u00e9 um estranho\u201d, um povo de Deus \u201cenriquecido por muitos povos\u201d. A Igreja, insistiu ele, n\u00e3o \u00e9 um \u201cpovo escolhido\u201d ou uma \u201celite religiosa\u201d.<\/p>\n<div id=\"aleteia-welcome\" style=\"text-align: justify;\"><\/div>\n<div class=\"nativo-inread\" style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">O Papa recordou ent\u00e3o a hist\u00f3ria do cristianismo na \u00c1sia Central, onde apareceu \u201cdesde os primeiros s\u00e9culos\u201d. Evocou tamb\u00e9m a mem\u00f3ria dos santos do Cazaquist\u00e3o, dando como exemplo o Beato Wladislaw Bukowi\u0144ski (1904-1974), um mission\u00e1rio em meio aos campos sovi\u00e9ticos que viveu entre prisioneiros e trabalhos for\u00e7ados.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cA f\u00e9 tem sido transmitida atrav\u00e9s da vida\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Francisco apelou a n\u00e3o \u201cperder a mem\u00f3ria\u201d desta evangeliza\u00e7\u00e3o cultivando uma forma de maravilhamento por esta \u201cgra\u00e7a\u201d. Mas tamb\u00e9m advertiu contra qualquer nostalgia que fa\u00e7a os crist\u00e3os ficarem bloqueados nas coisas do passado.<\/p>\n<p style=\"text-align: justify;\">\u201cA f\u00e9 foi transmitida atrav\u00e9s da vida\u201d, explicou Francisco, e n\u00e3o como \u201cum c\u00f3digo fixo duma uma vez por todas\u201d. A mensagem de Cristo \u00e9 um \u201cacontecimento sempre presente\u201d que deve ser transmitida como \u201cnovidade\u201d, insistiu ele.<\/p>\n<p style=\"text-align: justify;\">A fim de viver fraternalmente, o Papa Francisco encorajou a Igreja cazaque a assegurar que as suas comunidades, e em particular os semin\u00e1rios, sejam \u201cmas gin\u00e1sios de treino para a verdade, a abertura e a partilha\u201d e n\u00e3o ambientes \u201cr\u00edgidos e formais\u201d. A Igreja, salientou, \u201cdeve ser capaz de sair ao encontro do mundo\u201d.<\/p>\n<p style=\"text-align: justify;\">O Papa concluiu o encontro \u2013 o segundo do dia ap\u00f3s uma conversa privada com os jesu\u00edtas da regi\u00e3o \u2013 recitando uma ora\u00e7\u00e3o \u00e0 Virgem e depois um Pai-Nosso com a assembleia. Finalmente, aben\u00e7oou um \u00edcone de \u201cMaria, M\u00e3e da Grande Estepe\u201d. Esta tarde, dever\u00e1 ir ao Pal\u00e1cio da Independ\u00eancia para o seu discurso final na cerim\u00f3nia de encerramento do Congresso de L\u00edderes das Religi\u00f5es Mundiais e Tradicionais.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h3 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong>2 &#8220;S\u00d3 SERVINDO \u00c0 PAZ \u00c9 QUE O TEU NOME FICAR\u00c1 NA HIST\u00d3RIA\u201d, DIZ FRANCISCO AOS L\u00cdDERES MUNDIAIS<\/strong><\/h3>\n<p style=\"text-align: justify;\">Por Camille Dalmas, no Cazaquist\u00e3o: Denunciando a \u201cloucura sem sentido da guerra\u201d na conclus\u00e3o do 7\u00ba Congresso das Religi\u00f5es Mundiais e Tradicionais em Nur-Sultan a 15 de Setembro, o Papa Francisco colocou a sua visita ao Cazaquist\u00e3o na tradi\u00e7\u00e3o da de Jo\u00e3o Paulo II em 2001. Para a \u00faltima etapa da sua viagem a este pa\u00eds, o Papa encontrou-se com os l\u00edderes religiosos com quem foi assinada a Declara\u00e7\u00e3o Final. Este texto, que est\u00e1 de acordo com o Documento de Abu Dhabi, ser\u00e1 transmitido aos participantes na pr\u00f3xima Assembleia Geral da ONU.<\/p>\n<p style=\"text-align: justify;\">O Papa Francisco, referindo-se \u00e0 reuni\u00e3o de Assis organizada em 2002 por Jo\u00e3o Paulo II em rea\u00e7\u00e3o aos atentados de 11 de Setembro de 2001, recordou que hoje \u201co terrorismo pseudo-religioso, o extremismo, o radicalismo, o nacionalismo mascarado de sacralidade ainda suscitam receios e ansiedades sobre a religi\u00e3o\u201d. Salientou, nas palavras da Declara\u00e7\u00e3o Final deste Congresso, que \u201co extremismo, o radicalismo, o terrorismo e qualquer outro incitamento ao \u00f3dio, \u00e0 hostilidade, \u00e0 viol\u00eancia e \u00e0 guerra, independentemente da sua motiva\u00e7\u00e3o ou objetivo, n\u00e3o t\u00eam nada a ver com o verdadeiro esp\u00edrito religioso e devem ser rejeitados nos termos mais decisivos poss\u00edveis\u201d.<\/p>\n<p style=\"text-align: justify;\">Referindo-se ao simbolismo da bandeira do Cazaquist\u00e3o, entre a terra e o c\u00e9u, o Papa recordou a necessidade de uma \u201cdistin\u00e7\u00e3o\u201d entre \u201cpol\u00edtica e transcend\u00eancia\u201d, que n\u00e3o \u00e9 uma \u201cconfus\u00e3o\u201d nem uma \u201csepara\u00e7\u00e3o\u201d, \u201cporque as mais elevadas aspira\u00e7\u00f5es humanas n\u00e3o podem ser exclu\u00eddas da vida p\u00fablica e relegadas apenas para a esfera privada\u201d, disse ele.<\/p>\n<p style=\"text-align: justify;\">\u201cCada homem e cada mulher, na sua insubstitu\u00edvel singularidade, se estiverem em contato com o divino, podem irradiar uma luz particular sobre a terra\u201d, insistiu Francisco, colocando o di\u00e1logo inter-religioso na continuidade do Conc\u00edlio Vaticano II. Ele citou a Declara\u00e7\u00e3o Nostra Aetate, que recorda que \u201ctodos os povos formam uma s\u00f3 comunidade; t\u00eam uma s\u00f3 origem, uma vez que Deus fez todo o g\u00e9nero humano viver sobre a face da terra\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>O di\u00e1logo inter-religioso \u00e9 um caminho sem retorno<\/strong><\/p>\n<p style=\"text-align: justify;\">Rodeado pelo Presidente do Cazaquist\u00e3o, e n\u00e3o muito longe do Grande Im\u00e3 de Al-Azhar, do Rabino David Lau e do Metropolita Anthony de Volokolamsk, representando o Patriarcado de Moscou, Francisco martelou o ponto de vista de que \u201co caminho do di\u00e1logo inter-religioso \u00e9 um caminho comum de paz e para a paz e, como tal, \u00e9 necess\u00e1rio e sem retorno\u201d.<\/p>\n<p style=\"text-align: justify;\">Repetindo as palavras da Declara\u00e7\u00e3o, o Papa salientou que \u201ca paz \u00e9 urgente, porque hoje qualquer conflito militar ou foco de tens\u00e3o e confronto n\u00e3o pode deixar de provocar um nefasto \u00abefeito domin\u00f3\u00bb, comprometendo seriamente o sistema de rela\u00e7\u00f5es internacionais\u201d. O Papa fez este apelo direto aos l\u00edderes pol\u00edticos: \u201cempenhai-vos pela paz, n\u00e3o pelos armamentos! S\u00f3 servindo a paz \u00e9 que permanecer\u00e1 grande na hist\u00f3ria o vosso nome\u201d, advertiu.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m salientou a import\u00e2ncia de trabalhar para assegurar que as mulheres sejam \u201crespeitadas, reconhecidas e envolvidas\u201d. \u201cQuantas escolhas mort\u00edferas seriam evitadas se as mulheres estivessem no centro da tomada de decis\u00f5es\u201d, advertiu o Papa. Sublinhou tamb\u00e9m a import\u00e2ncia de educar os jovens, dizendo que \u201cas religiosidades r\u00edgidas e sufocantes n\u00e3o pertencem ao futuro, mas ao passado\u201d.<\/p>\n<p style=\"text-align: justify;\">Prestando homenagem ao car\u00e1cter multi-religioso e multicultural do Cazaquist\u00e3o, pelas suas \u00faltimas palavras em solo cazaque, o Bispo de Roma exortou a construir o futuro \u201csem esquecer a transcend\u00eancia e a fraternidade, a adora\u00e7\u00e3o do Alt\u00edssimo e o acolhimento do outro\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>A Declara\u00e7\u00e3o Final, um instrumento para a Assembleia Geral da ONU<\/strong><\/p>\n<p style=\"text-align: justify;\">A Declara\u00e7\u00e3o Final, que n\u00e3o foi assinada por todos os participantes, reconhece no seu pre\u00e2mbulo a import\u00e2ncia de \u201cenfrentar os desafios globais no nosso mundo p\u00f3s-pand\u00e9mico, incluindo as mudan\u00e7as clim\u00e1ticas, a pobreza e a fome; o crime organizado, o terrorismo e as drogas\u201d. Condena \u201cnos termos mais fortes poss\u00edveis o extremismo, o radicalismo e o terrorismo que levam \u00e0 persegui\u00e7\u00e3o religiosa e a ataques \u00e0 vida e dignidade humanas\u201d.<\/p>\n<p style=\"text-align: justify;\">Entre os 35 pontos do texto est\u00e1 tamb\u00e9m a afirma\u00e7\u00e3o de que a deflagra\u00e7\u00e3o de qualquer conflito militar, criando pontos quentes de tens\u00e3o e confronta\u00e7\u00e3o, provoca rea\u00e7\u00f5es em cadeia que prejudicam as rela\u00e7\u00f5es internacionais. Nenhuma situa\u00e7\u00e3o espec\u00edfica \u00e9 mencionada, embora as guerras na Ucr\u00e2nia e no C\u00e1ucaso estejam nas not\u00edcias.<\/p>\n<p style=\"text-align: justify;\">\u201cInstamos os governos nacionais e as organiza\u00e7\u00f5es internacionais autorizadas a prestarem assist\u00eancia abrangente a todos os grupos religiosos e comunidades \u00e9tnicas que tenham sido v\u00edtimas de viola\u00e7\u00f5es dos direitos humanos e de viol\u00eancia por extremistas e terroristas\u201d, escrevem tamb\u00e9m os signat\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Dizem tamb\u00e9m esperar que o Congresso forne\u00e7a ferramentas \u00e0s administra\u00e7\u00f5es p\u00fablicas dos diferentes pa\u00edses do mundo e \u00e0s institui\u00e7\u00f5es das Na\u00e7\u00f5es Unidas. A Declara\u00e7\u00e3o ser\u00e1 distribu\u00edda como documento oficial aos participantes na 77\u00aa Assembleia Geral da ONU, que abre em Nova Iorque na segunda-feira, 19 de Setembro.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h3 class=\"wp-block-aleteia-rich-list\" style=\"text-align: justify;\"><strong>3 DO CAZAQUIST\u00c3O, D. SCHNEIDER ADVERTE O PAPA SOBRE OS RISCOS DO DI\u00c1LOGO INTER-RELIGIOSO<\/strong><\/h3>\n<p style=\"text-align: justify;\">Por Camille Dalmas, Cazaquist\u00e3o \u2013 Questionado \u00e0 margem de um encontro entre o Papa Francisco e l\u00edderes cat\u00f3licos no Cazaquist\u00e3o a 15 de Setembro, o Bispo Auxiliar Athanasius Schneider, de Nur-Sultan, avisou o Papa Francisco que os encontros inter-religiosos a que assiste poderiam tornar-se \u201cum supermercado de religi\u00f5es\u201d. Conhecido pelos seus muitos desentendimentos com o Papa, o prelado conservador disse ser seu dever expressar os seus pontos de vista \u201cfraternalmente\u201d.<\/p>\n<p style=\"text-align: justify;\">O bispo auxiliar da capital do Cazaquist\u00e3o, D. Schneider, disse a um grupo de jornalistas o que sentia sobre a visita do Papa ao Cazaquist\u00e3o. Come\u00e7ou por reconhecer que a visita era de grande import\u00e2ncia para a pequena minoria cat\u00f3lica, \u201cum pequeno rebanho\u201d presente neste territ\u00f3rio onde os mu\u00e7ulmanos e os ortodoxos vivem em maioria.<\/p>\n<p style=\"text-align: justify;\"><strong>O Papa, uma figura sagrada<\/strong><\/p>\n<p style=\"text-align: justify;\">O homem que vem de uma fam\u00edlia alem\u00e3 deportada ap\u00f3s a Segunda Guerra Mundial tamb\u00e9m explicou que o Papa era considerado aqui como \u201cuma figura sagrada\u201d, que a sua mensagem de amor e respeito m\u00fatuo era importante para alimentar o povo cazaque.<\/p>\n<p style=\"text-align: justify;\">Mas foi sobre a cimeira inter-religiosa que reuniu mais de 80 l\u00edderes religiosos de todo o mundo que o Bispo Schneider se mostrou mais c\u00e9tico. \u201cO Congresso procura justamente promover o respeito e a compreens\u00e3o m\u00fatuos no mundo de hoje. Mas h\u00e1 tamb\u00e9m um perigo, porque poderia dar a impress\u00e3o de um supermercado de religi\u00f5es\u201d, advertiu ele.<\/p>\n<p style=\"text-align: justify;\">\u201cNeste encontro, a Igreja Cat\u00f3lica aparece visualmente, a partir do exterior, como uma das religi\u00f5es. Isto \u00e9, do meu ponto de vista, um aspecto negativo e perigoso\u201d, lamentou o prelado que considera que a miss\u00e3o da Igreja \u00e9 anunciar a natureza \u00fanica e absoluta de Jesus Cristo a todas as na\u00e7\u00f5es. O bispo Schneider salientou tamb\u00e9m o risco das repercuss\u00f5es deste tipo de encontro. \u201cPode ser utilizado pelas elites pol\u00edticas\u201d, advertiu.<\/p>\n<p style=\"text-align: justify;\"><strong>Como bispos, somos irm\u00e3os<\/strong><\/p>\n<p style=\"text-align: justify;\">Questionado por jornalistas sobre os seus desacordos recorrentes com o Papa Francisco, o bispo considerou que este n\u00e3o era um problema particular. \u201cComo bispos, somos irm\u00e3os. Ele \u00e9 o irm\u00e3o mais velho, o chefe da Igreja, mas quando, em consci\u00eancia, vejo que algo n\u00e3o est\u00e1 correto, ou \u00e9 amb\u00edguo, tenho de lhe dizer respeitosamente, fraternalmente\u201d, disse ele.<\/p>\n<p style=\"text-align: justify;\">Para ele, expressar os seus desacordos com o Papa \u00e9 \u201cverdadeiro amor fraternal\u201d. Ser bispo n\u00e3o \u00e9 o mesmo que \u201ccomportar-se como um empregado com o seu chefe\u201d. Pelo contr\u00e1rio, \u201cdizer quando se considera que existe um perigo para a Igreja \u00e9 oferecer uma verdadeira ajuda ao Papa\u201d, afirmou ele.<\/p>\n<p style=\"text-align: justify;\">Nascido em 1961 em Tomok, na ent\u00e3o Rep\u00fablica Socialista Sovi\u00e9tica do Quirguizist\u00e3o, o Bispo Schneider manifestou publicamente, em muitas ocasi\u00f5es, as suas discord\u00e2ncias com o Papa Francisco. Defensor dos Cardeais Burke, Brandm\u00fcller, Caffarra e Meisner, que expressaram as suas\u00a0<em>dubia<\/em>\u00a0em 2016 ap\u00f3s a publica\u00e7\u00e3o da exorta\u00e7\u00e3o apost\u00f3lica Amoris Laetitia, o Bispo Schneider foi tamb\u00e9m altamente cr\u00edtico do Documento de Abu Dhabi sobre a Fraternidade Humana para a Paz Mundial e a Coexist\u00eancia Comum assinado em 2019 pelo Papa Francisco e pelo Grande Im\u00e3 Ahmed al-Tayeb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boletim Direto do Vaticano de 16 de setembro de 2022 Nem \u201cadministradores do sagrado\u201d nem \u201cpol\u00edcias\u201d: a mensagem do Papa aos l\u00edderes cat\u00f3licos no Cazaquist\u00e3o \u201cS\u00f3 servindo \u00e0 paz \u00e9 que o teu nome ficar\u00e1 na hist\u00f3ria\u201d, diz Francisco aos l\u00edderes mundiais Do Cazaquist\u00e3o, D. Schneider adverte o Papa sobre os riscos do di\u00e1logo inter-religioso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75990,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-75989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-featured"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/75989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=75989"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/75989\/revisions"}],"predecessor-version":[{"id":75991,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/75989\/revisions\/75991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/75990"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=75989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=75989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=75989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}