{"id":74145,"date":"2022-06-01T10:16:19","date_gmt":"2022-06-01T13:16:19","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=74145"},"modified":"2022-06-01T15:20:21","modified_gmt":"2022-06-01T18:20:21","slug":"celebracoes-rodas-de-conversa-lives-vigilias-e-atos-ecumenicos-marcam-a-souc-2022-no-brasil","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/celebracoes-rodas-de-conversa-lives-vigilias-e-atos-ecumenicos-marcam-a-souc-2022-no-brasil\/","title":{"rendered":"CELEBRA\u00c7\u00d5ES, RODAS DE CONVERSA, LIVES, VIG\u00cdLIAS E ATOS ECUM\u00caNICOS MARCAM A SOUC 2022 NO BRASIL"},"content":{"rendered":"<p style=\"text-align: justify;\">Celebra\u00e7\u00f5es, rodas de conversa, vig\u00edlias, lives e atividades conjuntas entre Igrejas Crist\u00e3s marcam a realiza\u00e7\u00e3o da Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3s (SOUC) deste ano no Brasil. Em Bras\u00edlia (DF), o Conselho Nacional de Igrejas Crist\u00e3s (Conic) realizou a abertura na Catedral Anglicana, dia 30, \u00e0s 19h. A abertura da Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3 foi na Catedral Anglicana da capital. Al\u00e9m das representa\u00e7\u00f5es das igrejas crist\u00e3s, o momento tamb\u00e9m contou com a participa\u00e7\u00e3o de pessoas de outras confiss\u00f5es religiosas.<\/p>\n<p style=\"text-align: justify;\">O subsecret\u00e1rio adjunto de Pastoral e assessor da Comiss\u00e3o Episcopal Pastoral para o Ecumenismo e o Di\u00e1logo Inter-religioso da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), padre Marcus Barbosa, participou da celebra\u00e7\u00e3o representando a Igreja Cat\u00f3lica Apost\u00f3lica Romana. O padre enalteceu o clima acolhedor da Catedral Anglicana que recebeu as Igrejas Crist\u00e3s para a ora\u00e7\u00e3o pela unidade crist\u00e3 e abertura da SOUC.\u00a0\u201cFoi uma alegria nos reencontrarmos presencialmente, guardando, \u00e9 claro, os devidos cuidados com a pandemia que ainda n\u00e3o acabou\u201d, disse.<\/p>\n<h3 style=\"text-align: justify;\">Realidade do povo palestino<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-914387 alignright lazyloaded\" src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-264x300.jpg\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-264x300.jpg 264w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-500x569.jpg 500w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa.jpg 736w\" alt=\"\" width=\"264\" height=\"300\" data-srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-264x300.jpg 264w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-500x569.jpg 500w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa.jpg 736w\" data-src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Jovem-da-Igreja-Siria-Ortodoxa-264x300.jpg\" data-sizes=\"(max-width: 264px) 100vw, 264px\" \/>De acordo com padre Marcus Barbosa, a celebra\u00e7\u00e3o teve como um ponto forte a prega\u00e7\u00e3o feita pela jovem Maynara, da Igreja Sirian Ortodoxa, que se encontra em Bras\u00edlia, compartilhando, especialmente, as alegrias e as dores do povo da palestino.<\/p>\n<blockquote><p>\u201cDestaco ainda a criativa proposta de Celebra\u00e7\u00e3o preparada pelo Conselho de Igrejas do Oriente M\u00e9dio e adaptada no Brasil pelo CONIC agreste pernambucano\u201d, disse o assessor para a Comiss\u00e3o para o Ecumenismo da CNBB.<\/p><\/blockquote>\n<h3 style=\"text-align: justify;\">Atividades pelo Brasil<\/h3>\n<p style=\"text-align: justify;\">Na\u00a0<strong>diocese de Jundiai (SP)<\/strong>,\u00a0 o bispo diocesano, dom Vicente Costa, participou de uma Celebra\u00e7\u00e3o Ecum\u00eanica de abertura da Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3, dia 31 de maio. O ato ecum\u00eanico aconteceu na biblioteca p\u00fablica municipal \u201cProfessor Nelson Foot\u201d com representantes de Igrejas Crist\u00e3s e do Conselho de Pastores de Jundia\u00ed (CONPAS).<\/p>\n<figure id=\"attachment_914384\" class=\"wp-caption aligncenter\" style=\"text-align: justify;\" aria-describedby=\"caption-attachment-914384\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-914384 size-full lazyloaded\" src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP.png\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP.png 716w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP-300x181.png 300w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP-500x302.png 500w\" alt=\"\" width=\"716\" height=\"433\" data-srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP.png 716w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP-300x181.png 300w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP-500x302.png 500w\" data-src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Bispo-Jundiai-SP.png\" data-sizes=\"(max-width: 716px) 100vw, 716px\" \/><figcaption id=\"caption-attachment-914384\" class=\"wp-caption-text\">O bispo de Jundia\u00ed (SP), dom Vicente Costa, participou de ato ecum\u00eanico na abertura SOUC | Foto: Ascom Jundiai.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Na Par\u00f3quia S\u00e3o Pedro Ap\u00f3stolo, na\u00a0<strong>arquidiocese de S\u00e3o Paulo<\/strong>, neste dia 1\u00ba\u00a0 \u00e0s 20h, acontece uma vig\u00edlia de Ora\u00e7\u00e3o aberta a todos os crist\u00e3os que queiram rezar juntos pelo crescimento da comunh\u00e3o com Deus e entre os crist\u00e3os, como Jesus mesmo desejou: \u201cPara que todos sejam um, como tu, Pai, est\u00e1s em mim e eu em ti. (Jo 17, 21).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-914385 size-medium lazyloaded\" src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-300x300.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-300x300.jpg 300w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-1024x1024.jpg 1024w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-150x150.jpg 150w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-768x768.jpg 768w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-800x800.jpg 800w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-500x500.jpg 500w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC.jpg 1080w\" alt=\"\" width=\"300\" height=\"300\" data-srcset=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-300x300.jpg 300w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-1024x1024.jpg 1024w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-150x150.jpg 150w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-768x768.jpg 768w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-800x800.jpg 800w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-500x500.jpg 500w, https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC.jpg 1080w\" data-src=\"https:\/\/eadn-wc02-718006.nxedge.io\/cdn\/wp-content\/uploads\/2022\/06\/Programacao-SOUC-em-SC-300x300.jpg\" data-sizes=\"(max-width: 300px) 100vw, 300px\" \/>A prov\u00edncia de\u00a0<strong>Curitiba (PR)<\/strong>\u00a0da Rede Vicentina de Educa\u00e7\u00e3o preparou uma a\u00e7\u00e3o de comunica\u00e7\u00e3o da Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3 (SOUC). No material, eles\u00a0 refor\u00e7aram: \u201cOremos juntos\/as para que possamos ser instrumento de unidade nos diferentes espa\u00e7os em que estamos\u201d.<\/p>\n<p style=\"text-align: justify;\">A Faculdade Cat\u00f3lica da<strong>\u00a0Santa Catarina<\/strong>, com seu N\u00facleo de Estudos e Pesquisa em Ecumenismo e Dialogo Inter-religioso (NEDIR), e a Comiss\u00e3o Arquidiocesana de Ecumenismo e Di\u00e1logo Inter-religioso (CADEIR) prepararam uma programa\u00e7\u00e3o para a Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3 (SOUC).<\/p>\n<p style=\"text-align: justify;\">Nesta quarta-feira, 1\u00ba junho, dentro das programa\u00e7\u00e3o semanal da SOUC na\u00a0<strong>arquidiocese de Belo Horizonte (MG)<\/strong>\u00a0acontece, \u00e0s 19h, a Celebra\u00e7\u00e3o Ecum\u00eanica do Movimento Focolares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebra\u00e7\u00f5es, rodas de conversa, vig\u00edlias, lives e atividades conjuntas entre Igrejas Crist\u00e3s marcam a realiza\u00e7\u00e3o da Semana de Ora\u00e7\u00e3o pela Unidade Crist\u00e3s (SOUC) deste ano no Brasil. Em Bras\u00edlia (DF), o Conselho Nacional de Igrejas Crist\u00e3s (Conic) realizou a abertura na Catedral Anglicana, dia 30, \u00e0s 19h. A abertura da Semana de Ora\u00e7\u00e3o pela Unidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,13],"tags":[],"class_list":["post-74145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cnbb","category-featured"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/74145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=74145"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/74145\/revisions"}],"predecessor-version":[{"id":74147,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/74145\/revisions\/74147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/74146"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=74145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=74145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=74145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}