{"id":70187,"date":"2021-09-24T08:40:08","date_gmt":"2021-09-24T11:40:08","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=70187"},"modified":"2021-09-24T16:00:09","modified_gmt":"2021-09-24T19:00:09","slug":"o-papa-ao-novo-patriarca-armenio-proximo-aos-sofrimentos-da-siria-e-do-libano","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/o-papa-ao-novo-patriarca-armenio-proximo-aos-sofrimentos-da-siria-e-do-libano\/","title":{"rendered":"O Papa ao novo Patriarca arm\u00eanio: pr\u00f3ximo aos sofrimentos da S\u00edria e do L\u00edbano"},"content":{"rendered":"<div class=\"article__subTitle\" style=\"text-align: justify;\">Na carta entregue ao novo patriarca, o Santo Padre afirma que foi informado sobre sua elei\u00e7\u00e3o e se une na alegria dos filhos e filhas dessa Igreja e da Igreja universal que acompanharam com a ora\u00e7\u00e3o os Bispos reunidos primeiro no L\u00edbano, e nesses dias, em Roma, no Pontif\u00edcio Col\u00e9gio Arm\u00eanio, no S\u00ednodo dos Bispos da Igreja Patriarcal da Cil\u00edcia dos Arm\u00eanios.<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text \">\n<p style=\"text-align: justify;\"><b>Mariangela Jaguraba &#8211; Vatican News<\/b><\/p>\n<p style=\"text-align: justify;\">O Papa Francisco concedeu a Comunh\u00e3o Eclesi\u00e1stica ao novo patriarca da Cil\u00edcia dos Arm\u00eanios, dom Rapha\u00ebl Bedros XXI Minassian, eleito na \u00faltima quarta-feira (23\/09), no S\u00ednodo dos Bispos da Igreja Patriarcal da Cil\u00edcia dos Arm\u00eanios.<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"article__innerTitle\">Ou\u00e7a e compartilhe<\/div>\n<div>\n<audio class=\"wp-audio-shortcode\" id=\"audio-70187-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2021\/09\/24\/15\/136194378_F136194378.mp3?_=1\" \/><a href=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2021\/09\/24\/15\/136194378_F136194378.mp3\">https:\/\/media.vaticannews.va\/media\/audio\/s1\/2021\/09\/24\/15\/136194378_F136194378.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">Na carta entregue ao novo patriarca, o Santo Padre afirma que foi informado sobre sua elei\u00e7\u00e3o e se une na alegria dos filhos e filhas dessa Igreja e da Igreja universal, que acompanharam com a ora\u00e7\u00e3o os Bispos reunidos primeiro no L\u00edbano, e nesses dias, em Roma, no Pontif\u00edcio Col\u00e9gio Arm\u00eanio, no S\u00ednodo dos Bispos da Igreja Patriarcal da Cil\u00edcia dos Arm\u00eanios. &#8220;Cada membro do povo santo de Deus cat\u00f3lico arm\u00eanio esperava o seu Pastor, para ser conhecido por ele, chamado pelo nome e conduzido pela palavra forte e af\u00e1vel do Evangelho&#8221;, ressalta Francisco.<\/p>\n<p style=\"text-align: justify;\">Segundo o Papa, &#8220;a elei\u00e7\u00e3o de Sua Beatitude realizou-se num momento em que as pessoas s\u00e3o particularmente provadas por v\u00e1rios desafios. Penso nos sofrimentos da S\u00edria e do L\u00edbano, pa\u00edses onde a Igreja da Cil\u00edcia dos Arm\u00eanios est\u00e1 presente, e tamb\u00e9m na pandemia, que ainda est\u00e1 longe de ser superada em muitas partes do mundo. Todos os homens de boa vontade, especialmente os crist\u00e3os, s\u00e3o chamados a estar pr\u00f3ximos e a se mostrar irm\u00e3os, vencendo a indiferen\u00e7a e a solid\u00e3o. Mesmo sob os dil\u00favios da hist\u00f3ria e nos desertos de nossa \u00e9poca, podemos e devemos caminhar em dire\u00e7\u00e3o ao Crucificado que Ressuscitou&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;Conhecemos o povo arm\u00eanio como um especialista em sofrimento, pelas muitas prova\u00e7\u00f5es ao longo dos mais de 1.700 anos de hist\u00f3ria crist\u00e3, mas tamb\u00e9m por sua capacidade inexaur\u00edvel de florescer e dar fruto, atrav\u00e9s da santidade e sabedoria de seus santos e m\u00e1rtires, da cultura de seus m\u00e9dicos e pensadores, da arte que sabe gravar o sinal da cruz na rocha como \u00e1rvore da vida, testemunho da vit\u00f3ria da f\u00e9 sobre todas as for\u00e7as adversas do mundo&#8221;, ressalta o Pont\u00edfice na carta.<\/p>\n<p style=\"text-align: justify;\">Francisco recorda que a Igreja que sua Beatitude Rapha\u00ebl Bedros XXI Minassian &#8220;foi chamado para guiar est\u00e1 plenamente inserida nas vicissitudes do povo arm\u00eanio, preservando a sua mem\u00f3ria e tradi\u00e7\u00f5es, e ao mesmo tempo profundamente ligada ao Sucessor do Ap\u00f3stolo Pedro. Confio-lhes o cuidado das novas gera\u00e7\u00f5es, a promo\u00e7\u00e3o das voca\u00e7\u00f5es, a s\u00e1bia harmonia que voc\u00eas devem ser capazes de encontrar entre as diferentes inst\u00e2ncias de sua comunidade, tais como as Irm\u00e3s da Imaculada Concei\u00e7\u00e3o, a Congrega\u00e7\u00e3o Mekhitarista e o Instituto do Clero Patriarcal de Bzommar como muitos de seus filhos e filhas que se formaram e vivem na Igreja latina, mas est\u00e3o bem cientes de sua perten\u00e7a arm\u00eania&#8221;.<\/p>\n<p style=\"text-align: justify;\">O Papa exorta a olhar para o exemplo da Virgem Maria e dos santos, como S\u00e3o Greg\u00f3rio de Narek que ele teve a alegria de proclamar doutor da Igreja. &#8220;Que eles nos indiquem o caminho da fraternidade aut\u00eantica e do di\u00e1logo ecum\u00eanico com os irm\u00e3os da Igreja Apost\u00f3lica Arm\u00eania&#8221;, ressalta.<\/p>\n<p style=\"text-align: justify;\">Por fim, o Papa concede a &#8220;comunh\u00e3o eclesi\u00e1stica solicitada, de acordo com a Tradi\u00e7\u00e3o e as normas em vigor&#8221;.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na carta entregue ao novo patriarca, o Santo Padre afirma que foi informado sobre sua elei\u00e7\u00e3o e se une na alegria dos filhos e filhas dessa Igreja e da Igreja universal que acompanharam com a ora\u00e7\u00e3o os Bispos reunidos primeiro no L\u00edbano, e nesses dias, em Roma, no Pontif\u00edcio Col\u00e9gio Arm\u00eanio, no S\u00ednodo dos Bispos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,3],"tags":[],"class_list":["post-70187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/70187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=70187"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/70187\/revisions"}],"predecessor-version":[{"id":70189,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/70187\/revisions\/70189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/70188"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=70187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=70187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=70187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}