{"id":62022,"date":"2020-09-02T09:26:44","date_gmt":"2020-09-02T12:26:44","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=62022"},"modified":"2020-09-02T12:36:42","modified_gmt":"2020-09-02T15:36:42","slug":"papa-sexta-feira-dia-mundial-de-oracao-e-jejum-pelo-libano","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/papa-sexta-feira-dia-mundial-de-oracao-e-jejum-pelo-libano\/","title":{"rendered":"Papa: sexta-feira, Dia mundial de ora\u00e7\u00e3o e jejum pelo L\u00edbano"},"content":{"rendered":"<div class=\"article__subTitle\" style=\"text-align: justify;\">O Papa dedicou um longo tempo da Audi\u00eancia Geral desta quarta-feira ao L\u00edbano, convocando um dia de jejum e ora\u00e7\u00e3o para a pr\u00f3xima sexta-feira e enviando o cardeal Pietro Parolin ao Pa\u00eds dos Cedros naquele dia.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\n<div id='gallery-1' class='gallery galleryid-62022 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-7-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-7-2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-6-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-6-2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-5-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-5-2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-4-5.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-4-5-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-3-6.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.1000.563-3-6-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.750.422-48.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/cq5dam.thumbnail.cropped.750.422-48-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text\">\n<p style=\"text-align: justify;\"><b>Vatican News<\/b><\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"article__innerTitle\">Ou\u00e7a e compartilhe!<\/div>\n<div>\n<audio class=\"wp-audio-shortcode\" id=\"audio-62022-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/09\/02\/11\/135704909_F135704909.mp3?_=1\" \/><a href=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/09\/02\/11\/135704909_F135704909.mp3\">https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/09\/02\/11\/135704909_F135704909.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">A \u201cquerida popula\u00e7\u00e3o do L\u00edbano\u201d voltou a merecer a aten\u00e7\u00e3o do Papa, desta vez ao final da Audi\u00eancia Geral desta quarta-feira, 2, a primeira realizada na presen\u00e7a de p\u00fablico desde mar\u00e7o.<\/p>\n<p style=\"text-align: justify;\">Francisco dedicou quase que uma \u201csegunda catequese\u201d \u00e0 situa\u00e7\u00e3o vivida pelo Pa\u00eds dos Cedros. A profunda crise s\u00f3cio-pol\u00edtica-econ\u00f4mica foi agravada pela catastr\u00f3fica explos\u00e3o no porto de Beirute no in\u00edcio de agosto. E recordando as palavras pronunciadas por S\u00e3o Jo\u00e3o Paulo II h\u00e1 30 anos, afirmou:<\/p>\n<p style=\"text-align: justify;\"><i>Diante das repetidas trag\u00e9dias que cada um dos habitantes desta terra conhece, tomemos consci\u00eancia do extremo perigo que amea\u00e7a a pr\u00f3pria exist\u00eancia do pa\u00eds. O L\u00edbano n\u00e3o pode ser abandonado em sua solid\u00e3o.<\/i><\/p>\n<h2 style=\"text-align: justify;\">O L\u00edbano \u00e9 uma mensagem de liberdade<\/h2>\n<p style=\"text-align: justify;\">O Pont\u00edfice observou que \u201cpor mais de cem anos, o L\u00edbano foi um pa\u00eds de esperan\u00e7a\u201d, e que os libaneses \u201cconservaram sua f\u00e9 em Deus e demonstraram a capacidade de fazer de sua terra um lugar de toler\u00e2ncia, de respeito, de conviv\u00eancia, \u00fanico na regi\u00e3o\u201d:<\/p>\n<p style=\"text-align: justify;\"><i>A afirma\u00e7\u00e3o de que o L\u00edbano representa algo mais do que um Estado \u00e9 profundamente verdadeira: o L\u00edbano \u00e9 uma mensagem de liberdade, \u00e9 um exemplo de pluralismo tanto para o Oriente como para o Ocidente. Pelo bem do pr\u00f3prio pa\u00eds, mas tamb\u00e9m do mundo, n\u00e3o podemos permitir que este patrim\u00f4nio se perca.<\/i><\/p>\n<p style=\"text-align: justify;\">Ao povo liban\u00eas, o Santo Padre encoraja a perseverar na esperan\u00e7a e a encontrar energia para recome\u00e7ar. Aos pol\u00edticos e aos l\u00edderes religiosos, pede para olharem para o bem comum e de se esfor\u00e7arem com sinceridade e transpar\u00eancia na obra de reconstru\u00e7\u00e3o.<\/p>\n<h2 style=\"text-align: justify;\">F\u00e9 e ora\u00e7\u00e3o<\/h2>\n<p style=\"text-align: justify;\">Um apelo tamb\u00e9m \u00e9 dirigido \u00e0 comunidade internacional, para que ajude o pa\u00eds a sair desta grave crise. J\u00e1 aos habitantes de Beirute, exorta a recobrarem a coragem:<\/p>\n<p style=\"text-align: justify;\"><i>Que a f\u00e9 e a ora\u00e7\u00e3o sejam a vossa for\u00e7a. N\u00e3o abandonem suas casas e sua heran\u00e7a, n\u00e3o deixem cair o sonho daqueles que acreditaram no futuro de um pa\u00eds belo e pr\u00f3spero.<\/i><\/p>\n<h2 style=\"text-align: justify;\">Dar o exemplo e viver a pobreza, ao lado da popula\u00e7\u00e3o<\/h2>\n<p style=\"text-align: justify;\">Ent\u00e3o, um chamado aos sacerdotes, religiosos e religiosas da Igreja local, para que estejam pr\u00f3ximos de seu povo, sendo os primeiros a dar exemplo de pobreza e humildade, \u201cagentes de conc\u00f3rdia\u201d e de \u201cuma verdadeira cultura do encontro\u201d. \u201cNada de luxo, vivam na pobreza com vosso povo. Sejam exemplo!\u201d, pediu aos sacerdotes. \u201cSomente olhando para o interesse comum, continua o Papa, ser\u00e1 poss\u00edvel \u201cassegurar a continuidade da presen\u00e7a crist\u00e3 e a sua inestim\u00e1vel contribui\u00e7\u00e3o ao pa\u00eds, ao mundo \u00e1rabe e a toda a regi\u00e3o, num esp\u00edrito de fraternidade entre todas as tradi\u00e7\u00f5es religiosas que existem no L\u00edbano&#8221;.<\/p>\n<h2 style=\"text-align: justify;\">O an\u00fancio do dia de ora\u00e7\u00e3o<\/h2>\n<p style=\"text-align: justify;\">Ent\u00e3o, a convoca\u00e7\u00e3o de um dia de ora\u00e7\u00e3o pelo Pa\u00eds dos Cedros, iniciativa muito aplaudida pelos presentes:<\/p>\n<p style=\"text-align: justify;\"><i>Gostaria de convidar a todos a viver um dia universal de ora\u00e7\u00e3o e jejum pelo L\u00edbano, na pr\u00f3xima sexta-feira, 4 de setembro. Tenho a inten\u00e7\u00e3o de enviar o meu representante ao L\u00edbano naquele dia para acompanhar a popula\u00e7\u00e3o. Nesse dia, o secret\u00e1rio de Estado ir\u00e1 em meu nome. E ele ir\u00e1, para expressar minha proximidade e solidariedade. Ofere\u00e7amos nossas ora\u00e7\u00f5es por todo o L\u00edbano e por Beirute. Estamos pr\u00f3ximos tamb\u00e9m com o compromisso concreto da caridade, como em outras ocasi\u00f5es semelhantes. Convido tamb\u00e9m os irm\u00e3os e irm\u00e3s de outras confiss\u00f5es e tradi\u00e7\u00f5es religiosas a se unirem a esta iniciativa nas modalidades que considerarem mais adequada, mas todos juntos.<\/i><\/p>\n<h2 style=\"text-align: justify;\">O agradecimento do sacerdote liban\u00eas<\/h2>\n<p style=\"text-align: justify;\">\u201cObrigado, Santidade. Precisamos muito do seu apoio e do apoio da Igreja universal para dizer: \u201cN\u00e3o podemos continuar a viver assim no L\u00edbano\u201d. At\u00e9 agora,\u00a0<b>mais de trezentos mil crist\u00e3os apresentaram seus documentos para a emigra\u00e7\u00e3o.<\/b>\u00a0Precisamos de sua ora\u00e7\u00e3o, de seu apoio e de seu amor fraternal. E o esperamos para aben\u00e7oar nossa amada terra. Obrigado Santidade. Muito obrigado.\u201d<\/p>\n<p style=\"text-align: justify;\">Ao final, o pedido de intercess\u00e3o \u00e0 Virgem Maria e o convite a todos para se levantarem para um momento de ora\u00e7\u00e3o silenciosa pelo L\u00edbano.<\/p>\n<p style=\"text-align: justify;\">E ent\u00e3o, em um momento muito tocante, as palavras de agradecimento do sacerdote liban\u00eas, padre Georges Braydi, que segurando uma bandeira do L\u00edbano esteve ao lado do Papa Francisco durante os apelos pelo seu pa\u00eds.<\/p>\n<div>\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"embed-container\" style=\"text-align: justify;\"><iframe id=\"796878033\" src=\"https:\/\/www.youtube.com\/embed\/EBfMXfFMNrI?wmode=opaque&amp;rel=0&amp;autohide=1&amp;showinfo=0&amp;wmode=transparent&amp;modestbranding=1&amp;enablejsapi=1&amp;origin=https:\/\/www.vaticannews.va&amp;start=&amp;end=\" allowfullscreen=\"allowfullscreen\" data-gtm-yt-inspected-7781034_9=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div class=\"article__innerTitle\" style=\"text-align: justify;\">Papa anuncia para 4 de setembro um dia de ora\u00e7\u00f5es pelo L\u00edbano<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Papa dedicou um longo tempo da Audi\u00eancia Geral desta quarta-feira ao L\u00edbano, convocando um dia de jejum e ora\u00e7\u00e3o para a pr\u00f3xima sexta-feira e enviando o cardeal Pietro Parolin ao Pa\u00eds dos Cedros naquele dia. Vatican News Ou\u00e7a e compartilhe! A \u201cquerida popula\u00e7\u00e3o do L\u00edbano\u201d voltou a merecer a aten\u00e7\u00e3o do Papa, desta vez [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62023,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,3],"tags":[],"class_list":["post-62022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/62022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=62022"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/62022\/revisions"}],"predecessor-version":[{"id":62030,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/62022\/revisions\/62030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/62023"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=62022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=62022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=62022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}