{"id":61799,"date":"2020-08-26T09:31:41","date_gmt":"2020-08-26T12:31:41","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=61799"},"modified":"2020-08-26T12:33:11","modified_gmt":"2020-08-26T15:33:11","slug":"familia-encontro-mundial-sera-em-2022-recordamos-o-papa-em-dublin-2018","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/familia-encontro-mundial-sera-em-2022-recordamos-o-papa-em-dublin-2018\/","title":{"rendered":"Fam\u00edlia: Encontro Mundial ser\u00e1 em 2022. Recordamos o Papa em Dublin 2018"},"content":{"rendered":"<p style=\"text-align: justify;\">Cerim\u00f4nia de boas-vindas no Knock Shrine, em County Maio, em agosto de 2018, no segundo dia da visita \u00e0 Irlanda\u00a0 (AFP or licensors)<\/p>\n<div class=\"article__subTitle\" style=\"text-align: justify;\">O X Encontro Mundial das Fam\u00edlias foi adiado para o ano 2022 devido \u00e0 pandemia e ter\u00e1 lugar em Roma. A \u00faltima edi\u00e7\u00e3o foi em agosto de 2018 em Dublin na Irlanda e o Papa exortou as fam\u00edlias para a revolu\u00e7\u00e3o do amor.<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text\">\n<p style=\"text-align: justify;\"><b>Rui Saraiva &#8211; Porto<\/b><\/p>\n<p style=\"text-align: justify;\">Devido \u00e0 pandemia do novo coronav\u00edrus que estamos a viver, a X edi\u00e7\u00e3o do Encontro Mundial das Fam\u00edlias foi adiada para 2022 sendo anulado o agendamento para 2021. Ser\u00e1 Roma a cidade que vai acolher uma organiza\u00e7\u00e3o t\u00e3o importante que decorrer\u00e1 durante o m\u00eas de junho de 2022.<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"article__innerTitle\">Ou\u00e7a e compartilhe!<\/div>\n<div>\n<audio class=\"wp-audio-shortcode\" id=\"audio-61799-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/08\/19\/09\/135689453_F135689453.mp3?_=1\" \/><a href=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/08\/19\/09\/135689453_F135689453.mp3\">https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/08\/19\/09\/135689453_F135689453.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">A \u00faltima edi\u00e7\u00e3o foi em agosto de 2018 em Dublin na Irlanda com a presen\u00e7a do Papa Francisco. Logo no primeiro dia, 25 de agosto, o Santo Padre teve um encontro na Pr\u00f3-Catedral de Santa Maria. A\u00ed foi acolhido por in\u00fameros casais, alguns j\u00e1 av\u00f3s, outros rec\u00e9m-casados e outros ainda noivos que saudaram e colocaram quest\u00f5es ao Santo Padre. A todos o Papa ouviu com aten\u00e7\u00e3o tendo depois proferido um discurso no qual procurou responder a cada uma das inquieta\u00e7\u00f5es apresentadas. S\u00e3o esses e outros momentos que aqui recordamos.<\/p>\n<h2 style=\"text-align: justify;\">Matrim\u00f3nio, voca\u00e7\u00e3o para toda a vida<\/h2>\n<h2 style=\"text-align: justify;\"><\/h2>\n<p style=\"text-align: justify;\">Francisco come\u00e7ou por agradecer o testemunho do casal Vincent e Teresa, que falaram brevemente da sua experi\u00eancia de cinquenta anos de matrim\u00f3nio e de vida familiar.<\/p>\n<p style=\"text-align: justify;\">Depois dirigiu-se ao casal de noivos Denis e Sinead e disse-lhes que \u201co matrim\u00f3nio n\u00e3o \u00e9 simplesmente uma institui\u00e7\u00e3o, mas uma voca\u00e7\u00e3o, uma decis\u00e3o consciente e para toda a vida de ocupar-se, ajudar-se e proteger-se mutuamente.\u201d Francisco assinalou que num matrim\u00f3nio h\u00e1 sempre lit\u00edgios, mas o mais importante \u00e9 que ap\u00f3s uma discuss\u00e3o e antes de ir dormir seja feita a paz entre marido e mulher.<\/p>\n<p style=\"text-align: justify;\">Francisco alertou para os perigos da \u201ccultura do provis\u00f3rio e do ef\u00e9mero\u201d e de um amor que n\u00e3o seja para toda a vida. \u201cEntre todas as formas da fecundidade humana, o matrim\u00f3nio \u00e9 \u00fanico\u201d \u2013 lembrou o Papa salientando que \u201co sacramento do matrim\u00f3nio, participa de modo especial no mist\u00e9rio do amor eterno de Deus\u201d \u2013 afirmou.<\/p>\n<p style=\"text-align: justify;\">Destaque especial para uma hist\u00f3ria pessoal que o Papa contou na resposta ao casal rec\u00e9m-casado Stephen e Jordan que perguntaram ao Papa como poder\u00e3o transmitir a f\u00e9 aos seus filhos. O Santo Padre sublinhou que tudo come\u00e7a em casa, no lar, na \u201cigreja dom\u00e9stica\u201d e recordou uma pequena experi\u00eancia pessoal de quando tinha cinco anos.<\/p>\n<p style=\"text-align: justify;\">O pequeno Jorge Bergoglio viu o pai e a m\u00e3e que se beijavam: \u201cque os vossos filhos vos vejam beijar e acariciar e aprendam o dialeto do amor e da f\u00e9\u201d \u2013 declarou o Papa aos casais irlandeses.<\/p>\n<p style=\"text-align: justify;\">O Santo Padre real\u00e7ou ainda a import\u00e2ncia da ora\u00e7\u00e3o em fam\u00edlia e a viv\u00eancia da solidariedade com aqueles que sofrem. \u201cO mundo diz-nos para sermos fortes e independentes, preocupando-nos pouco com aqueles que est\u00e3o sozinhos ou tristes, rejeitados ou doentes\u201d \u2013 disse o Papa afirmando que \u201co nosso mundo precisa duma revolu\u00e7\u00e3o de amor! Que esta revolu\u00e7\u00e3o comece por v\u00f3s e pelas vossas fam\u00edlias!\u201d<\/p>\n<p style=\"text-align: justify;\">\u201cOs vossos filhos aprender\u00e3o de v\u00f3s a viver como crist\u00e3os; sereis os seus primeiros mestres na f\u00e9\u201d \u2013 afirmou ainda o Santo Padre que frisou que \u201cn\u00e3o poder\u00e1 haver uma revolu\u00e7\u00e3o de amor, sem a revolu\u00e7\u00e3o da ternura!\u201c<\/p>\n<p style=\"text-align: justify;\">No final do seu discurso o Papa real\u00e7ou a import\u00e2ncia do di\u00e1logo e do conv\u00edvio entre gera\u00e7\u00f5es: \u201cas crian\u00e7as n\u00e3o crescem no amor se n\u00e3o aprendem a comunicar com os seus av\u00f3s. Ent\u00e3o deixai que o vosso amor lance ra\u00edzes profundas!\u201d \u2013 afirmou Francisco.<\/p>\n<h2 style=\"text-align: justify;\">Esperan\u00e7a da Igreja e do mundo<\/h2>\n<h2 style=\"text-align: justify;\"><\/h2>\n<p style=\"text-align: justify;\">Grande momento com o Papa no IX Encontro Mundial das Fam\u00edlias foi a Festa das Fam\u00edlias no Croke Park Stadium em Dublin na Irlanda. O Santo Padre afirmou no seu discurso que a fam\u00edlia \u00e9 a esperan\u00e7a da Igreja e do mundo: \u201cv\u00f3s, fam\u00edlias, sois a esperan\u00e7a da Igreja e do mundo\u201d \u2013 afirmou.<\/p>\n<p style=\"text-align: justify;\">Foram v\u00e1rios e intensos os testemunhos de fam\u00edlias que apresentaram experi\u00eancias de vida matrimonial e familiar, vividas em v\u00e1rias partes do mundo. O Papa referiu-se a estes testemunhos proferindo um discurso continuamente aplaudido pela multid\u00e3o presente no est\u00e1dio.<\/p>\n<p style=\"text-align: justify;\">Francisco considerou a Festa das Fam\u00edlias como uma verdadeira \u201ccelebra\u00e7\u00e3o familiar de a\u00e7\u00e3o de gra\u00e7as a Deus pelo que somos\u201d \u2013 disse o Papa \u2013 \u201cuma \u00fanica fam\u00edlia em Cristo, espalhada pela terra\u201d.<\/p>\n<p style=\"text-align: justify;\">O Santo Padre defendeu o Batismo das crian\u00e7as em tenra idade para que fa\u00e7am parte, desde pequeninas, da grande fam\u00edlia de Deus. O Papa salientou que o \u201cEvangelho da fam\u00edlia \u00e9, verdadeiramente, alegria para o mundo\u201d, pois nas \u201cnossas fam\u00edlias, sempre se pode encontrar Jesus\u201d que \u201cl\u00e1 habita, em simplicidade e pobreza, como fez na casa da Sagrada Fam\u00edlia de Nazar\u00e9\u201d \u2013 assinalou.<\/p>\n<p style=\"text-align: justify;\">Todos os membros da fam\u00edlia s\u00e3o chamados \u00e0 realiza\u00e7\u00e3o do amor com gestos simples e humildes, em particular, na viv\u00eancia da escuta, da compreens\u00e3o e do perd\u00e3o. Francisco recordou as tr\u00eas palavras-chave para a paz na fam\u00edlia que permitem superar o orgulho e o isolamento:<\/p>\n<p style=\"text-align: justify;\">\u201c\u2026 precisamos de aprender tr\u00eas palavras: \u00abdesculpa\u00bb, \u00abpor favor\u00bb e \u00abobrigado\u00bb.<\/p>\n<p style=\"text-align: justify;\">O Papa recordou que, antes de ir dormir, \u00e9 importante fazer a paz na vida de casal. \u201cPerdoar significa doar algo de si mesmo. Jesus perdoa-nos sempre. Com a for\u00e7a do seu perd\u00e3o, tamb\u00e9m n\u00f3s podemos perdoar aos outros, se o quisermos de verdade\u201d \u2013 disse ainda o Papa salientando que os filhos aprendem a perdoar quando veem os seus pais perdoarem-se entre si.<\/p>\n<p style=\"text-align: justify;\">O Santo Padre falou tamb\u00e9m das redes sociais, fazendo refer\u00eancia ao testemunho de um casal da \u00cdndia, e pediu que as novas tecnologias sejam usadas com \u201cmodera\u00e7\u00e3o e prud\u00eancia\u201d pois podem \u201ccontribuir para a constru\u00e7\u00e3o duma rede de amizade, solidariedade e apoio m\u00fatuo\u201d.<\/p>\n<p style=\"text-align: justify;\">Recordando a Exorta\u00e7\u00e3o Apost\u00f3lica \u201cA alegria do amor\u201d, o Papa, referindo-se ao testemunho de uma fam\u00edlia com dez filhos, sublinhou que o \u201camor conjugal\u201d \u00e9 caraterizado pela \u201cfidelidade, indissolubilidade, unidade e abertura \u00e0 vida\u201d.<\/p>\n<p style=\"text-align: justify;\">O primeiro Encontro Mundial das Fam\u00edlias teve lugar em Roma em 1994 com S. Jo\u00e3o Paulo II. Organiza-se normalmente a cada 3 anos e j\u00e1 passou pelas cidades de Rio de Janeiro, Manila, Val\u00eancia, Cidade do M\u00e9xico, Mil\u00e3o e Filad\u00e9lfia. Em 2018 foi em Dublin na Irlanda e o Papa Francisco sublinhou a beleza da voca\u00e7\u00e3o ao matrim\u00f3nio exortando as fam\u00edlias para a revolu\u00e7\u00e3o do amor e da ternura sendo esperan\u00e7a da Igreja e do mundo.<\/p>\n<p style=\"text-align: justify;\"><i>Laudetur Iesus Christus<\/i><\/p>\n<\/div>\n<div id=\"banner-donazioni\" class=\"article_banner\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cerim\u00f4nia de boas-vindas no Knock Shrine, em County Maio, em agosto de 2018, no segundo dia da visita \u00e0 Irlanda\u00a0 (AFP or licensors) O X Encontro Mundial das Fam\u00edlias foi adiado para o ano 2022 devido \u00e0 pandemia e ter\u00e1 lugar em Roma. A \u00faltima edi\u00e7\u00e3o foi em agosto de 2018 em Dublin na Irlanda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-61799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/61799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=61799"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/61799\/revisions"}],"predecessor-version":[{"id":61801,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/61799\/revisions\/61801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/61800"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=61799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=61799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=61799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}