{"id":60944,"date":"2020-07-24T09:19:32","date_gmt":"2020-07-24T12:19:32","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=60944"},"modified":"2020-07-24T11:20:49","modified_gmt":"2020-07-24T14:20:49","slug":"oms-conclui-primeira-conferencia-sobre-epidemia-de-fake-news","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/oms-conclui-primeira-conferencia-sobre-epidemia-de-fake-news\/","title":{"rendered":"OMS conclui primeira confer\u00eancia sobre epidemia de fake news"},"content":{"rendered":"<h2 class=\"subtitle\" style=\"text-align: justify;\">Infodemia, como \u00e9 chamada a superpropaga\u00e7\u00e3o de informa\u00e7\u00e3o, se alastra na velocidade de um v\u00edrus e custa vidas<\/h2>\n<div class=\"base-post-content\">Apandemia do novo coronav\u00edrus chegou em um momento muito particular e perigoso da hist\u00f3ria, pois ele coincide com o hiper-fluxo de informa\u00e7\u00f5es, uma realidade que j\u00e1 viv\u00edamos antes do surgimento da Covid-19.<\/p>\n<p style=\"text-align: justify;\">Como informa\u00e7\u00e3o precisa e de qualidade \u00e9 essencial no combate ao v\u00edrus, a dissemina\u00e7\u00e3o de not\u00edcias falsas atrapalha e muito na conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o e na divulga\u00e7\u00e3o dos cuidados necess\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">A situa\u00e7\u00e3o est\u00e1 t\u00e3o grave que pela primeira vez na hist\u00f3ria a Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) realizou, ao longo de tr\u00eas semanas, uma confer\u00eancia cient\u00edfica com 110 especialistas de 14 \u00e1reas diferentes para debater os efeitos da infodemia, como \u00e9 chamada a dissemina\u00e7\u00e3o sem crit\u00e9rio de informa\u00e7\u00f5es, que foi conclu\u00edda nesta ter\u00e7a-feira (21).<\/p>\n<p style=\"text-align: justify;\">Os especialistas demonstraram preocupa\u00e7\u00e3o especial com not\u00edcias falsas que est\u00e3o custando vidas. Tanto que ainda no in\u00edcio da pandemia a organiza\u00e7\u00e3o criou uma p\u00e1gina na internet com o intuito de desmentir informa\u00e7\u00f5es falsas.<\/p>\n<p style=\"text-align: justify;\">Nos Estados Unidos, por exemplo, ap\u00f3s o presidente Donald Trump ter falado da boca para fora que a ingest\u00e3o de desinfetante ajudaria a eliminar o v\u00edrus, a cidade de Nova York registrou 30 chamados hospitalares de indiv\u00edduos que beberam produtos equivalentes \u00e0 C\u00e2ndida e quase morreram. No Ir\u00e3, mais de 700 pessoas perderam a vida ap\u00f3s consumirem metanol na esperan\u00e7a de matar o v\u00edrus.<\/p>\n<p style=\"text-align: justify;\">O mesmo vale para o consumo de medicamentos como hidroxicloroquina e azitromicina, que n\u00e3o t\u00eam efic\u00e1cia comprovada por nenhum \u00f3rg\u00e3o de sa\u00fade respeit\u00e1vel e podem trazer efeitos colaterais. Na Fran\u00e7a, ap\u00f3s diversos \u00f3bitos por problemas card\u00edacos associados ao uso de hidroxicloroquina, a indica\u00e7\u00e3o ao uso do medicamento foi suspensa.<\/p>\n<div class=\"nativo-inread\" style=\"text-align: justify;\"><\/div>\n<div id=\"aleteia-welcome\" style=\"text-align: justify;\" data-google-query-id=\"CKL1sMCK5uoCFcsmuQYdBCsPBw\">\n<div id=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0__container__\"><iframe id=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-google-container-id=\"2\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p style=\"text-align: justify;\">No Reino Unido, ap\u00f3s circular a teoria da conspira\u00e7\u00e3o de que a pandemia estaria relacionada \u00e0 tecnologia 5G, quase 100 torres de sinal do pa\u00eds foram incendiadas e funcion\u00e1rios de operadoras foram atacados, aumentando o tumulto e desviando, assim, foco e recursos do combate \u00e0 pandemia.<\/p>\n<p style=\"text-align: justify;\">A OMS alegou que em um mundo com mais e mais celulares conectados \u00e0 internet, mensagens falsas se alastram pelas redes sociais e por aplicativos de mensagens na velocidade de um v\u00edrus. Para os participantes do semin\u00e1rio, a solu\u00e7\u00e3o exige uma abordagem multidisciplinar por parte da comunidade cient\u00edfica de diversos aspectos da dissemina\u00e7\u00e3o de informa\u00e7\u00f5es falsas.<\/p>\n<p style=\"text-align: justify;\">E da conscientiza\u00e7\u00e3o de cada um, que, como a pr\u00f3pria OMS apontou, tem sua parcela de responsabilidade e deve fazer sua parte: n\u00e3o compartilhando informa\u00e7\u00f5es antes de confirm\u00e1-las.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Infodemia, como \u00e9 chamada a superpropaga\u00e7\u00e3o de informa\u00e7\u00e3o, se alastra na velocidade de um v\u00edrus e custa vidas Apandemia do novo coronav\u00edrus chegou em um momento muito particular e perigoso da hist\u00f3ria, pois ele coincide com o hiper-fluxo de informa\u00e7\u00f5es, uma realidade que j\u00e1 viv\u00edamos antes do surgimento da Covid-19. Como informa\u00e7\u00e3o precisa e de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":60945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-60944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=60944"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60944\/revisions"}],"predecessor-version":[{"id":60946,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60944\/revisions\/60946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/60945"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=60944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=60944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=60944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}