{"id":60239,"date":"2020-06-25T09:54:47","date_gmt":"2020-06-25T12:54:47","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=60239"},"modified":"2020-06-25T12:00:52","modified_gmt":"2020-06-25T15:00:52","slug":"papa-envia-2500-kits-de-testes-para-diagnostico-de-covid-19-a-gaza","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/papa-envia-2500-kits-de-testes-para-diagnostico-de-covid-19-a-gaza\/","title":{"rendered":"Papa envia 2500 kits de testes para diagn\u00f3stico de Covid-19 a Gaza"},"content":{"rendered":"<div style=\"text-align: justify;\">A entrega dos kits doados pelo Papa ao Minist\u00e9rio da Sa\u00fade de Gaza<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div class=\"article__subTitle\" style=\"text-align: justify;\">At\u00e9 agora, os Territ\u00f3rios Palestinos registram 1328 casos de Covid-19, mas a baixa porcentagem de pessoas testadas positivas poderia ser um ind\u00edcio da falta de testes realizados. \u201cOs 2500 kits enviados pelo Papa v\u00e3o nos ajudar a fazer diagn\u00f3sticos mais precisos. Em toda a Faixa existe apenas uma m\u00e1quina que pode fazer as an\u00e1lises para mais de 2 milh\u00f5es de pessoas\u201d, afirmou Pe. Romanelli, p\u00e1roco de Gaza.<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text\">\n<p style=\"text-align: justify;\"><b>Alessandro Guarasci &#8211; Vatican News<\/b><\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--unwrap article__embed--dark\">\n<div class=\"article__innerTitle\">Ou\u00e7a a reportagem e compartilhe<\/div>\n<div>\n<audio class=\"wp-audio-shortcode\" id=\"audio-60239-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/06\/25\/11\/135638150_F135638150.mp3?_=1\" \/><a href=\"https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/06\/25\/11\/135638150_F135638150.mp3\">https:\/\/media.vaticannews.va\/media\/audio\/s1\/2020\/06\/25\/11\/135638150_F135638150.mp3<\/a><\/audio>\n<\/div>\n<div class=\"article__innerTitle\">O Papa doou 2500 testes de Covid-19 ao Minist\u00e9rio da Sa\u00fade de Gaza, atrav\u00e9s da Congrega\u00e7\u00e3o para as Igrejas Orientais. A entrega dos kits, que aconteceu no \u00faltimo dia 17 de junho, foi coordenada pela Delega\u00e7\u00e3o Apost\u00f3lica, pelo Patriarcado Latino de Jerusal\u00e9m e pela Caritas de Jerusal\u00e9m. A not\u00edcia foi divulgada pelo pr\u00f3prio Patriarcado.<\/div>\n<\/div>\n<\/div>\n<h2 style=\"text-align: justify;\">A caridade do Papa<\/h2>\n<p style=\"text-align: justify;\">Os kits foram entregues pela Caritas Jerusal\u00e9m e pelo Pe. Gabriel Romanelli, p\u00e1roco latino da Sagrada Fam\u00edlia em Gaza. A doa\u00e7\u00e3o faz parte das iniciativas promovidas pelo Fundo de Emerg\u00eancia, desejado pelo Papa Francisco, para ajudar os pa\u00edses mais afetados pela dissemina\u00e7\u00e3o da Covid-19. Entre eles, a S\u00edria que recebeu 10 ventiladores, outros tr\u00eas foram doados para o Hospital S\u00e3o Jos\u00e9 em Jerusal\u00e9m, enquanto os kits com testes de Covid-19 foram enviados ao Hospital da Sagrada Fam\u00edlia em Bel\u00e9m.<\/p>\n<div style=\"text-align: justify;\">\n<aside class=\"article__readmore\">\n<div class=\"teaser--labelEvidence teaser teaser--type-article\">\n<article>\n<div class=\"teaser__labelWrapper\"><\/div>\n<div class=\"teaser__contentWrapper\">\n<div>A doa\u00e7\u00e3o do Papa faz parte dos muitos \u201ccarinhos\u201d com que Francisco se faz presente e pr\u00f3ximo: fundos que s\u00e3o um oxig\u00eanio para \u00e1reas em dificuldade e, depois, respiradores, material m\u00e9dico, kits sanit\u00e1rios que viajam de uma parte do mundo para a outra, do Equador \u00e0 Rom\u00eania, do Brasil \u00e0 Espanha, a N\u00e1poles e a Lecce. Mas, tamb\u00e9m, telefonemas que chegam a bispos, comunidades, m\u00e9dicos, enfermeiros que vivem o sofrimento e a dificuldade, tanto nos corredores dos hospitais como nas c\u00farias ou nas associa\u00e7\u00f5es de voluntariado na linha de frente. Para cada um, uma palavra ou um gesto e muita gratid\u00e3o.<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/aside>\n<\/div>\n<h2 style=\"text-align: justify;\">A falta de testes e leitos em Gaza<\/h2>\n<p style=\"text-align: justify;\">Com a propaga\u00e7\u00e3o do v\u00edrus em Gaza, onde vivem cerca de 2 milh\u00f5es de pessoas, as autoridades locais de sa\u00fade lamentaram a falta de testes para fazer diagn\u00f3sticos e tamb\u00e9m solicitaram 100 ventiladores e 140 leitos para as UTIs. Segundo o Minist\u00e9rio da Sa\u00fade da Palestina, Gaza registra 72 casos de Covid-19 (15 ainda est\u00e3o ativos) de um total de 1328 casos nos Territ\u00f3rios Palestinos (dados de 25 de junho).<\/p>\n<p style=\"text-align: justify;\">A baixa porcentagem de pessoas testadas positivas poderia ser um ind\u00edcio da falta de testes realizados. A Caritas de Jerusal\u00e9m e o Minist\u00e9rio da Sa\u00fade de Gaza, como informa o Patriarcado Latino, &#8220;prepararam um plano de emerg\u00eancia que prev\u00ea, entre outras coisas, a presta\u00e7\u00e3o de servi\u00e7os m\u00e9dicos no Centro da Caritas e a ativa\u00e7\u00e3o de tr\u00eas equipes m\u00e9dicas m\u00f3veis para realizar servi\u00e7o domiciliar no tratamento de pacientes n\u00e3o-Covid-19 durante as 24 horas do dia&#8221;. Como em Israel, tamb\u00e9m na Cisjord\u00e2nia foram registrados novos picos de infec\u00e7\u00e3o nas \u00faltimas duas semanas: o mais alto em Hebron com 551 casos, seguido de Nablus com 32.<\/p>\n<h2 style=\"text-align: justify;\">O p\u00e1roco de Gaza: al\u00e9m da Covid-19, a grave situa\u00e7\u00e3o econ\u00f4mica<\/h2>\n<p style=\"text-align: justify;\">Segundo o Pe. Gabriel Romanelli, p\u00e1roco latino da Sagrada Fam\u00edlia em Gaza, nos Territ\u00f3rios Palestinos &#8220;h\u00e1 uma emerg\u00eancia de coronav\u00edrus, mas ela est\u00e1 ligada a muitas outras situa\u00e7\u00f5es\u201d. O sacerdote cita, ent\u00e3o, \u201co bloqueio da fronteira com Israel ou Egito, o fechamento de muitas atividades comerciais, como os restaurantes. Dessa forma, muitas pessoas perderam o emprego e ficaram sem sal\u00e1rio. Os professores das nossas escolas n\u00e3o foram demitidos, mas o Patriarcado teve dificuldade em pagar os sal\u00e1rios&#8221;.<\/p>\n<p style=\"text-align: justify;\">O fechamento de Gaza pesa mais do que nunca neste momento, explica o p\u00e1roco, mas as poucas entradas conseguiram conter o cont\u00e1gio pelo v\u00edrus. O Pe. Romanelli acrescenta que todos os casos que tiveram \u201cdizem respeito a pessoas que vieram de fora e que foram imediatamente colocadas em quarentena. Os kits enviados pelo Papa v\u00e3o nos ajudar a fazer diagn\u00f3sticos mais precisos e, assim que os recebemos, levamos ao laborat\u00f3rio do Minist\u00e9rio da Sa\u00fade. Em toda Gaza, de fato, tem apenas uma m\u00e1quina que pode fazer as an\u00e1lises&#8221;.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A entrega dos kits doados pelo Papa ao Minist\u00e9rio da Sa\u00fade de Gaza At\u00e9 agora, os Territ\u00f3rios Palestinos registram 1328 casos de Covid-19, mas a baixa porcentagem de pessoas testadas positivas poderia ser um ind\u00edcio da falta de testes realizados. \u201cOs 2500 kits enviados pelo Papa v\u00e3o nos ajudar a fazer diagn\u00f3sticos mais precisos. Em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":60240,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,3],"tags":[],"class_list":["post-60239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=60239"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60239\/revisions"}],"predecessor-version":[{"id":60241,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/60239\/revisions\/60241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/60240"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=60239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=60239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=60239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}