{"id":56358,"date":"2020-01-22T08:49:50","date_gmt":"2020-01-22T11:49:50","guid":{"rendered":"https:\/\/catolicanet.net\/wp-cnet\/?p=56358"},"modified":"2020-01-22T08:49:50","modified_gmt":"2020-01-22T11:49:50","slug":"o-papa-a-hospitalidade-e-uma-virtude-ecumenica-que-exige-disposicao-para-ouvir-os-outros","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/o-papa-a-hospitalidade-e-uma-virtude-ecumenica-que-exige-disposicao-para-ouvir-os-outros\/","title":{"rendered":"O Papa: a hospitalidade \u00e9 uma virtude ecum\u00eanica que exige disposi\u00e7\u00e3o para ouvir os outros"},"content":{"rendered":"<div class=\"article__subTitle\" style=\"text-align: justify;\">Na Audi\u00eancia Geral desta quarta-feira, Francisco abordou o tema da Semana de Ora\u00e7\u00e3o pela Unidade dos Crist\u00e3os \u201cTrataram-nos com gentileza\u201d, partindo do Livro dos Atos dos Ap\u00f3stolos que fala sobre a hospitalidade dos habitantes de Malta para com S\u00e3o Paulo e seus companheiros de viagem que naufragaram com ele. O mar que fez Paulo naufragar junto com seus companheiros \u00e9 ainda \u201cum lugar perigoso para a vida de seus navegantes\u201d. &#8220;Homens e mulheres migrantes enfrentam viagens arriscadas para fugir da viol\u00eancia, da guerra e da pobreza.&#8221;<\/div>\n<div class=\"title__separator\" style=\"text-align: justify;\"><\/div>\n<div class=\"article__text\">\n<p style=\"text-align: justify;\"><b>Mariangela Jaguraba &#8211; Cidade do Vaticano<\/b><\/p>\n<p style=\"text-align: justify;\">A catequese da Audi\u00eancia Geral do Papa Francisco, nesta quarta-feira (22\/01), realizada na Sala Paulo VI, foi dedicada ao tema da Semana de Ora\u00e7\u00e3o pela Unidade dos Crist\u00e3os \u201cTrataram-nos com gentileza\u201d (At 28,2).<\/p>\n<p style=\"text-align: justify;\">Francisco sublinhou que o tema deste ano \u00e9 o da hospitalidade e foi desenvolvido pelas Igrejas crist\u00e3s de Malta e Gozo, a partir da passagem do Livro dos Atos dos Ap\u00f3stolos que fala sobre a hospitalidade dos habitantes de Malta para com S\u00e3o Paulo e seus companheiros de viagem que naufragaram com ele.<\/p>\n<p style=\"text-align: justify;\">O Papa iniciou, contando a experi\u00eancia dram\u00e1tica desse naufr\u00e1gio.<\/p>\n<p style=\"text-align: justify;\"><i>O navio em que Paulo viaja est\u00e1 \u00e0 merc\u00ea dos elementos. Durante\u00a0 catorze dias eles est\u00e3o no mar, e como nem o sol e nem as estrelas s\u00e3o vis\u00edveis, os viajantes se sentem desorientados, perdidos. Abaixo deles, o mar bate violentamente contra o navio e eles temem que o navio se rompa por causa da for\u00e7a das ondas. Do alto eles s\u00e3o a\u00e7oitados pelo vento e pela chuva. A for\u00e7a do mar e da tempestade \u00e9 terrivelmente poderosa e indiferente ao destino dos navegantes: mais de 260 pessoas!<\/i><\/p>\n<h2 style=\"text-align: justify;\">A hospitalidade comunica algo do amor de Deus<\/h2>\n<p style=\"text-align: justify;\">Por\u00e9m, Paulo sabe que n\u00e3o \u00e9 assim. A f\u00e9 lhe diz que a sua vida est\u00e1 nas m\u00e3os de Deus que ressuscitou Jesus dentre os mortos e chamou o Ap\u00f3stolo dos Gentios \u201cpara levar o Evangelho aos confins da terra. A sua f\u00e9 tamb\u00e9m lhe diz que Deus, segundo o que Jesus revelou, \u00e9 um Pai amoroso. Portanto, Paulo dirige-se a seus companheiros de viagem e, inspirado pela f\u00e9, anuncia a eles que Deus n\u00e3o permitir\u00e1 que um fio de cabelo deles seja perdido\u201d.\u00a0\u201cEssa profecia se torna realidade quando o navio encalha na costa de Malta e todos os passageiros chegam s\u00e3os e salvos a terra firme. Ali, eles experimentam algo novo. <b>Em contraste com a viol\u00eancia brutal do mar tempestuoso, eles recebem o testemunho da \u201chumanidade rara\u201d dos habitantes da ilha. Essas pessoas, desconhecidas, est\u00e3o atentas \u00e0s suas necessidades. Acendem uma fogueira para eles se aquecerem, lhes oferecem abrigo contra chuva e alimento. Mesmo que ainda n\u00e3o tenham recebido as Boa Nova de Cristo, manifestam o amor de Deus em atos concretos de bondade.<\/b> <b>De fato, a hospitalidade espont\u00e2nea e os gestos de carinho comunicam algo do amor de Deus, e a hospitalidade dos malteses \u00e9 recompensada pelos milagres de cura que Deus opera atrav\u00e9s de Paulo na ilha<\/b>. Portanto, se o povo de Malta foi um sinal da provid\u00eancia de Deus para o ap\u00f3stolo, ele tamb\u00e9m foi testemunha do amor misericordioso de Deus por ele.\u201d<\/p>\n<h2 style=\"text-align: justify;\">Hospitalidade, virtude ecum\u00eanica<\/h2>\n<p style=\"text-align: justify;\">A seguir, o Papa disse:<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--border embed_style\">\n<blockquote><p>\u201cQueridos, a hospitalidade \u00e9 importante; \u00e9 uma importante virtude ecum\u00eanica tamb\u00e9m. Primeiramente, significa reconhecer que outros crist\u00e3os s\u00e3o realmente nossos irm\u00e3os e irm\u00e3s em Cristo. N\u00f3s somos irm\u00e3os.\u201d<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><b>&#8220;Algu\u00e9m lhe dir\u00e1: &#8220;Mas esse \u00e9\u00a0 protestante, aquele \u00e9 ortodoxo &#8230;&#8221; Sim, mas somos irm\u00e3os em Cristo.<\/b> N\u00e3o \u00e9 um ato de generosidade numa s\u00f3 dire\u00e7\u00e3o, porque quando hospedamos outros crist\u00e3os, os acolhemos como um presente que nos \u00e9 dado. Como os malteses, bons malteses, somos recompensados, porque recebemos o que o Esp\u00edrito Santo semeou em nossos irm\u00e3os e irm\u00e3s, e isso se torna um presente para n\u00f3s tamb\u00e9m, porque o Esp\u00edrito Santo semeia suas gra\u00e7as em todos os lugares.\u201d<\/p>\n<p style=\"text-align: justify;\"><i>\u201cAcolher os crist\u00e3os de outra tradi\u00e7\u00e3o significa, primeiramente, mostrar o amor de Deus por eles, porque eles s\u00e3o filhos de Deus, nossos irm\u00e3os, e tamb\u00e9m significa acolher o que Deus realizou em suas vidas\u201d<\/i>, ressaltou Francisco.<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--border embed_style\">\n<blockquote><p>\u201cA hospitalidade ecum\u00eanica exige disposi\u00e7\u00e3o para ouvir os outros, prestando aten\u00e7\u00e3o em suas hist\u00f3rias pessoais de f\u00e9 e na hist\u00f3ria de sua comunidade, comunidade de f\u00e9 com outra tradi\u00e7\u00e3o diferente da nossa.\u201d<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">&#8220;A hospitalidade ecum\u00eanica envolve o desejo de conhecer a experi\u00eancia que outros crist\u00e3os t\u00eam de Deus e a expectativa de receber os dons espirituais que surgem. E isso \u00e9 uma gra\u00e7a; descobrir isso \u00e9 uma gra\u00e7a. Penso nos tempos passados, na minha terra, por exemplo. Quando alguns mission\u00e1rios evang\u00e9licos chegaram, um pequeno grupo de cat\u00f3licos foi queimar as tendas. Isso n\u00e3o. N\u00e3o \u00e9 crist\u00e3o. Somos irm\u00e3os, somos todos irm\u00e3os e devemos ser hospitaleiros uns com os outros.\u201d<\/p>\n<h2 style=\"text-align: justify;\">Migrantes enfrentam viagens arriscadas para fugir da viol\u00eancia<\/h2>\n<p style=\"text-align: justify;\">Francisco disse ainda que hoje, o mar que fez Paulo naufragar junto com seus companheiros \u00e9 ainda \u201cum lugar perigoso para a vida de seus navegantes\u201d.<\/p>\n<div style=\"text-align: justify;\">\n<div class=\"article__embed article__embed--border embed_style\">\n<blockquote><p>\u201cEm todo o mundo, homens e mulheres migrantes enfrentam viagens arriscadas para fugir da viol\u00eancia, da guerra e da pobreza. Como Paulo e seus companheiros, experimentam a indiferen\u00e7a, a hostilidade do deserto, dos rios, dos mares. Muitas vezes n\u00e3o deixam eles desembarcar nos portos. Infelizmente, \u00e0s vezes eles tamb\u00e9m encontram a hostilidade pior dos homens. S\u00e3o explorados por traficantes criminosos. Hoje! S\u00e3o tratados como n\u00fameros e como uma amea\u00e7a por alguns governantes. Hoje! \u00c0s vezes, a falta de hospitalidade os rejeita como uma onda em dire\u00e7\u00e3o \u00e0 pobreza ou aos perigos dos quais fugiram.\u201d<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">Francisco concluiu sua catequese, dizendo que <b>&#8220;n\u00f3s crist\u00e3os devemos trabalhar juntos para mostrar aos migrantes o amor de Deus revelado em Jesus Cristo&#8221;. <\/b>\u201cPodemos e devemos testemunhar que n\u00e3o h\u00e1 somente hostilidade e indiferen\u00e7a, mas que cada pessoa \u00e9 preciosa para Deus e amada por Ele. <i>Trabalhar juntos para viver a hospitalidade ecum\u00eanica, tornar\u00e1 todos os crist\u00e3os, protestantes, ortodoxos, cat\u00f3licos, todos os crist\u00e3os, seres humanos melhores, disc\u00edpulos melhores e um povo crist\u00e3o mais unido.\u201d\u00a0<\/i><\/p>\n<p style=\"text-align: justify;\">A Semana de Ora\u00e7\u00e3o pela Unidade dos Crist\u00e3os, no Hemisf\u00e9rio Norte, teve in\u00edcio no \u00faltimo dia 18 e prossegue at\u00e9 o pr\u00f3ximo dia 25. No Brasil, \u00e9 celebrada entre Ascens\u00e3o e Pentecostes.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na Audi\u00eancia Geral desta quarta-feira, Francisco abordou o tema da Semana de Ora\u00e7\u00e3o pela Unidade dos Crist\u00e3os \u201cTrataram-nos com gentileza\u201d, partindo do Livro dos Atos dos Ap\u00f3stolos que fala sobre a hospitalidade dos habitantes de Malta para com S\u00e3o Paulo e seus companheiros de viagem que naufragaram com ele. O mar que fez Paulo naufragar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,3],"tags":[],"class_list":["post-56358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/56358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=56358"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/56358\/revisions"}],"predecessor-version":[{"id":56360,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/56358\/revisions\/56360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/56359"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=56358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=56358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=56358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}