{"id":54278,"date":"2019-09-27T09:47:32","date_gmt":"2019-09-27T12:47:32","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=54278"},"modified":"2019-09-27T09:57:50","modified_gmt":"2019-09-27T12:57:50","slug":"semana-da-vida-2019-comissao-propoe-gestos-para-os-dias-1o-e-8-de-outubro","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/semana-da-vida-2019-comissao-propoe-gestos-para-os-dias-1o-e-8-de-outubro\/","title":{"rendered":"Semana da Vida 2019: Comiss\u00e3o prop\u00f5e gestos para os dias 1\u00ba e 8 de outubro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-54280\" src=\"http:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/vela_2-1-300x193.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/vela_2-1-300x193.jpg 300w, https:\/\/catolicanet.net\/wp-cnet\/wp-content\/uploads\/vela_2-1.jpg 465w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>De 1\u00ba a 8 de outubro, a Igreja no Brasil celebra a Semana Nacional da Vida e o Dia do Nascituro. A iniciativa, promovida pela Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), por meio da Comiss\u00e3o Episcopal Pastoral para a Vida e a Fam\u00edlia, prop\u00f5e neste ano o tema \u201cEm fam\u00edlia defendemos a vida! Com alegria e esperan\u00e7a\u201d. Em entrevista, o bispo de Rio Grande (RS) e presidente da Comiss\u00e3o, dom Ricardo Hoepers, fala da import\u00e2ncia desta semana, os gestos propostos e as dimens\u00f5es que s\u00e3o trabalhadas no \u00e2mbito eclesial e de incid\u00eancia na sociedade civil na defesa da vida \u201cdom de Deus\u201d.<\/p>\n<p>Dom Ricardo refor\u00e7a que a Comiss\u00e3o preparou uma iniciativa especial, que consiste em dois gestos: No dia 1\u00ba de outubro todas as Igrejas s\u00e3o convidadas a soar os sinos \u00e0s 12h, \u00e0s 15h e \u00e0s 18h e fazer a ora\u00e7\u00e3o do nascituro. Para o dia 8 de outubro, o convite \u00e9 para a vig\u00edlia pela vida: \u201cAcender o maior n\u00famero de velas, simbolizando a luz de Cristo, que d\u00e1 sentido \u00e0 nossa vida\u201d, sugere o bispo.<\/p>\n<p><strong><a href=\"https:\/\/www.cnbb.org.br\/?attachment_id=226202\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-226202 alignleft\" src=\"https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/folder-snv-2019-768x592-300x231.jpg\" srcset=\"https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/folder-snv-2019-768x592-300x231.jpg 300w, https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/folder-snv-2019-768x592.jpg 768w\" alt=\"\" width=\"300\" height=\"231\" \/><\/a>Qual a import\u00e2ncia da Semana Nacional da Vida?<\/strong><\/p>\n<blockquote><p><em>A Semana Nacional da Vida \u00e9 um momento oportuno de sensibilizar a sociedade civil como um todo e a pr\u00f3pria Igreja para a promo\u00e7\u00e3o e defesa da vida, desde a concep\u00e7\u00e3o at\u00e9 o fim natural. \u00c9 um momento e mobiliza\u00e7\u00e3o que n\u00f3s podemos mostrar ao mundo que a vida \u00e9 um dom de Deus, que a vida vale a pena, que a vida tem sentido e que a vida deve ser celebrada, sentida com alegria. \u00c9 tanto que estamos colocando como tema \u201cEm fam\u00edlia, defendemos a vida com alegria e esperan\u00e7a.<\/em><\/p><\/blockquote>\n<p><strong>Quais as propostas que a Comiss\u00e3o Episcopal para a Vida e a Fam\u00edlia tem incentivado neste ano?<\/strong><\/p>\n<blockquote>\n<div id=\"attachment_226199\" class=\"wp-caption alignright\">\n<p><a href=\"https:\/\/www.cnbb.org.br\/?attachment_id=226199\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-226199\" src=\"https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/Dom-Ricardo-Hoepers-300x162.png\" srcset=\"https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/Dom-Ricardo-Hoepers-300x162.png 300w, https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/Dom-Ricardo-Hoepers-768x416.png 768w, https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/Dom-Ricardo-Hoepers-1024x554.png 1024w, https:\/\/www.cnbb.org.br\/wp-content\/uploads\/sites\/32\/2019\/09\/Dom-Ricardo-Hoepers.png 1212w\" alt=\"\" width=\"300\" height=\"162\" aria-describedby=\"caption-attachment-226199\" \/><\/a><\/p>\n<p id=\"caption-attachment-226199\" class=\"wp-caption-text\"><em>Dom Ricardo Hoepers | Foto: CNBB\/Daniel Flores<\/em><\/p>\n<\/div>\n<p><em>As comunidades v\u00eam se mobilizando cada vez mais nessa Semana Nacional da Vida e temos o subs\u00eddio <a href=\"http:\/\/site.cnpf.org.br\/noticias\/vida\/em-familia-celebramos-a-vida-com-alegria-e-esperanca\/\">\u201cHora da Vida\u201d<\/a> que ali existem os encontros para as comunidades, os temas que podem ser abordados, \u00e9 um bom instrumento para o trabalho nessa Semana da vida. Mas neste ano temos algo bem especial. N\u00f3s estamos fazendo duas grandes mobiliza\u00e7\u00f5es. No in\u00edcio da semana, dia 1\u00ba de outubro, com o soar dos sinos, estamos pedindo que todas as Igrejas possam soar os sinos \u00e0s 12h, \u00e0s 15h e \u00e0s 18h e, nesses hor\u00e1rios, o Brasil inteiro se unir para fazer a ora\u00e7\u00e3o do nascituro. Ent\u00e3o \u00e9 um momento de sintonia, de alegria pelo dom da vida.<\/em><\/p>\n<p><em>E no dia 8 de outubro, n\u00f3s queremos fazer uma vig\u00edlia pela vida. Acender o maior n\u00famero de velas, simbolizando a luz de Cristo, que d\u00e1 sentido \u00e0 nossa vida. Ent\u00e3o n\u00f3s estamos convidando as comunidades para que se mobilizem, numa pra\u00e7a p\u00fablica, em frente a uma Igreja e possam tamb\u00e9m recitar as ora\u00e7\u00f5es pela vida e se mobilizarem em torno desses dois momentos: dia 1\u00ba de outubro o badalar dos sinos e no dia 8 de outubro a vig\u00edlia acendendo as velas pela vida.<\/em><\/p><\/blockquote>\n<p><strong>A motiva\u00e7\u00e3o principal que tem sido levada \u00e0s comunidades talvez seja a quest\u00e3o do nascituro, por conta do dia 8 de outubro. Mas, atualmente, a Igreja enfrenta v\u00e1rios ataques \u00e0 vida, como a quest\u00e3o do suic\u00eddio que tem relevo no m\u00eas de setembro. O subs\u00eddio Hora da Vida apresenta reflex\u00f5es a respeito dessas outras dimens\u00f5es e apresenta indica\u00e7\u00f5es para a a\u00e7\u00e3o Pastoral?<\/strong><\/p>\n<blockquote><p><em>Sem d\u00favida. N\u00f3s estamos tentando abranger a defesa da vida, tanto que \u00e9 a proposta desde a concep\u00e7\u00e3o at\u00e9 o fim natural. Ent\u00e3o, temos a quest\u00e3o de suic\u00eddios, as quest\u00f5es dos idosos, do abandono da vida. A cultura da morte vem se apresentando com for\u00e7a. N\u00f3s como Igreja, como homens e mulheres de f\u00e9, temos que propor a cultura da vida, em todas as etapas da vida. N\u00e3o s\u00f3 no in\u00edcio, mas em todas as etapas. E \u00e9 nisso que n\u00f3s acreditamos e \u00e9 para isso a Semana da Vida, que a gente possa se mobilizar mostrando que o ser humano precisa ser respeitado na sua dignidade f\u00edsica, corporal e espiritual. Acima de tudo, promo\u00e7\u00e3o da vida \u00e9 dizer \u2018a vida vale a pena porque \u00e9 dom de Deus\u2019\u201d.<\/em><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p>Neste ano, a mobiliza\u00e7\u00e3o em torno dos gestos para a Semana Nacional da Vida ganhou apoio das emissoras de televis\u00e3o e r\u00e1dio de inspira\u00e7\u00e3o cat\u00f3lica, que est\u00e3o divulgando a iniciativa dos sinos e das velas desde a \u00faltima semana. A Comiss\u00e3o Nacional da Pastoral Familiar (CNPF) oferece o <a href=\"http:\/\/site.cnpf.org.br\/noticias\/vida\/em-familia-celebramos-a-vida-com-alegria-e-esperanca\/\">subs\u00eddio Hora da Vida<\/a> para auxiliar grupos e comunidades nas reflex\u00f5es e celebra\u00e7\u00f5es da Semana Nacional da Vida.<\/p>\n<p>Reze a ora\u00e7\u00e3o pela vida:<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 1\u00ba a 8 de outubro, a Igreja no Brasil celebra a Semana Nacional da Vida e o Dia do Nascituro. A iniciativa, promovida pela Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), por meio da Comiss\u00e3o Episcopal Pastoral para a Vida e a Fam\u00edlia, prop\u00f5e neste ano o tema \u201cEm fam\u00edlia defendemos a vida! Com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54279,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-54278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/54278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=54278"}],"version-history":[{"count":2,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/54278\/revisions"}],"predecessor-version":[{"id":54288,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/54278\/revisions\/54288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/54279"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=54278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=54278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=54278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}