{"id":53330,"date":"2019-09-05T11:47:50","date_gmt":"2019-09-05T14:47:50","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=53330"},"modified":"2019-09-05T11:47:50","modified_gmt":"2019-09-05T14:47:50","slug":"primeira-carta-de-joao-quem-ama-permanece-em-deus","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/primeira-carta-de-joao-quem-ama-permanece-em-deus\/","title":{"rendered":"Primeira carta de Jo\u00e3o: Quem ama permanece em Deus"},"content":{"rendered":"<p>Publicado pela PAULUS Editora, a obra\u00a0<em>Primeira carta de Jo\u00e3o: Quem ama permanece em Deus,<\/em>\u00a0organizada por Luiz Alexandre Solano Rossi, apresenta ao leitor um dos escritos atribu\u00eddos a S\u00e3o Jo\u00e3o Evangelista.<\/p>\n<p>Ao longo das p\u00e1ginas desta obra ser\u00e3o analisados trechos da Carta acompanhados de coment\u00e1rios. As notas explicativas foram feitas pelo grupo de pesquisa \u201cB\u00edblia e Pastoral\u201d, da Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1, composta por professores, mestrandos e doutores em B\u00edblia, e tem o objetivo \u00e0 leitura e interpreta\u00e7\u00e3o das Sagradas Escrituras e posterior produ\u00e7\u00e3o de textos.<\/p>\n<p>Na introdu\u00e7\u00e3o da obra Vicente Artuso, doutor em Teologia, afirma que nos escritos joaninos existe uma rela\u00e7\u00e3o entre as cartas e o Evangelho, tanto no estilo, como no conte\u00fado. Ao longo do texto, o leitor ser\u00e1 apresentado ao contexto da comunidade de Jo\u00e3o, al\u00e9m dos conflitos teol\u00f3gicos de grupos com tend\u00eancias diversas e contr\u00e1rias entre os crist\u00e3os.<\/p>\n<p>Dividida em seis cap\u00edtulos, o volume introduz o leitor ao conte\u00fado da Primeira Carta de Jo\u00e3o. Na sequ\u00eancia, os autores se dividem para refletir cada cap\u00edtulo do livro. Dessa maneira o leitor ter\u00e1 base para ler e entender a Carta.<\/p>\n<p><strong>Autores:<\/strong>\u00a0<em>Alceu Luiz Orso (Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1 e Claretiano Studium Theologicum); Ildo Perondi (Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1); Luiz Alexandre Solano Rossi (Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1 e Centro Universit\u00e1rio Internacional); Vicente Artuso (Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado pela PAULUS Editora, a obra\u00a0Primeira carta de Jo\u00e3o: Quem ama permanece em Deus,\u00a0organizada por Luiz Alexandre Solano Rossi, apresenta ao leitor um dos escritos atribu\u00eddos a S\u00e3o Jo\u00e3o Evangelista. Ao longo das p\u00e1ginas desta obra ser\u00e3o analisados trechos da Carta acompanhados de coment\u00e1rios. As notas explicativas foram feitas pelo grupo de pesquisa \u201cB\u00edblia e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-53330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/53330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=53330"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/53330\/revisions"}],"predecessor-version":[{"id":53332,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/53330\/revisions\/53332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/53331"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=53330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=53330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=53330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}