{"id":52220,"date":"2019-08-12T08:10:07","date_gmt":"2019-08-12T11:10:07","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=52220"},"modified":"2019-08-13T08:22:22","modified_gmt":"2019-08-13T11:22:22","slug":"o-queijo-e-as-virtudes","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/o-queijo-e-as-virtudes\/","title":{"rendered":"O queijo e as virtudes"},"content":{"rendered":"<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>J\u00e1 vai longe o tempo em que a sociedade sabia dar valor \u00e0s pequenas virtudes. N\u00e3o que essas inexistam no campo pessoal dos que buscam uma vida agrad\u00e1vel. Sen\u00e3o aos olhos dos homens, ao menos aos olhos de Deus elas s\u00e3o preciosas Para muitos, virtudes s\u00e3o caretices, inven\u00e7\u00e3o de beatos. N\u00e3o combina com a voracidade dos tempos atuais. Para outros, \u00e9 uma pr\u00e1tica concernente \u00e0 vida religiosa, da qual pouqu\u00edssimos comungam coerentemente. Que cada qual cuide de seu queijo, sen\u00e3o o outro leva!<\/p>\n<p>Lembra aqui velha anedota escolar, quando um padre, um jovem pol\u00edtico e um caboclo viajavam juntos pelo sert\u00e3o. Numa casa seus moradores deram-lhes um pequeno peda\u00e7o de queijo, o pouco que podiam oferecer aos inesperados viajantes. Sem saber como dividir a pequena refei\u00e7\u00e3o, combinaram entre si de que o queijo seria daquele que, naquela noite, tivesse o sonho mais bonito.<\/p>\n<p>Na manh\u00e3 seguinte cada qual contou seu sonho. O padre, como lhe convinha pelos conhecimentos do of\u00edcio, disse ter sonhado que subia aos c\u00e9us pela escada de Jac\u00f3 e enquanto o fazia, contemplava um mundo cheio de gan\u00e2ncia e mis\u00e9ria, que deixava para tr\u00e1s sem nenhuma tristeza. O jovem pol\u00edtico, mais ardiloso, disse que, no sonho, j\u00e1 estava no c\u00e9u, \u00e0 espera do padre. E o caboclo?<\/p>\n<p>&#8211; Bem, eu sonhei que via o padre subindo a escada, enquanto o doutorzinho aqui j\u00e1 o esperava no c\u00e9u. Gritava aos dois que voltassem, pois esqueceram o queijo. Como n\u00e3o me responderam e como j\u00e1 gozavam das alegrias do c\u00e9u, comi o queijo&#8230;<\/p>\n<p>N\u00e3o importa o sonho. A realidade \u00e9 que, enquanto muitos tecem planos para se apossarem das prendas que pensam merecer; enquanto a l\u00e1bia de alguns produz teorias e planos para surrupiar egoisticamente o que um gesto de partilha, mesmo do pouco, contentaria a todos, Deus d\u00e1 aos pobres a intelig\u00eancia necess\u00e1ria para receberem o quinh\u00e3o que os mant\u00eam vivos.<\/p>\n<p>A verdade \u00e9 que todos constroem suas interpreta\u00e7\u00f5es de virtudes, desde que delas possam se aproveitar, receber algum benef\u00edcio. Infelizmente, tanto no campo religioso, quanto no campo pol\u00edtico, as interpreta\u00e7\u00f5es se moldam mais aos interesses pessoais. Enquanto sonham com um para\u00edso pessoal, pobres se contentam com as migalhas de uma cruel realidade. N\u00e3o fosse essa paciente e obstinada virtude da simplicidade e da sabedoria popular, o que seria daqueles que pensam conduzir o destino do povo? Que sonham gozar das alegrias celestes ainda em vida? Que caminham com o povo com o olhar gordo sobre o pouco que lhes sobra? Que ambicionam at\u00e9 o \u00faltimo naco de um queijo mal partilhado?<\/p>\n<p>Nenhuma virtude ter\u00e1 valor, nenhum dogma religioso, nenhum ideal pol\u00edtico, se n\u00e3o houver por primeiro a pr\u00e1tica da caridade, rainha das virtudes. Por primeiro, o pequeno, o pobre. Depois, sim, poderemos sonhar com nosso para\u00edso pessoal. \u201cAspirai aos dons superiores. E agora, ainda vou indicar-vos o caminho mais excelente de todos\u201d (1Cor 12,21). A caridade n\u00e3o se restringe a um simples peda\u00e7o de queijo. Com uma ren\u00fancia, mesmo que circunstancial, ela ser\u00e1 aut\u00eantica. Pois cinco p\u00e3es e um peixe alimentaram uma multid\u00e3o no deserto. N\u00e3o sonhe com o c\u00e9u nas alturas, quando por primeiro devemos sonhar com o c\u00e9u entre n\u00f3s. Pois que a escada de Jac\u00f3 \u00e9 o caminho mais curto entre o C\u00e9u e a Terra&#8230;, desde que saibamos partilhar com justi\u00e7a aquelas sacas de trigo distribu\u00eddas entre irm\u00e3os. Sem trapa\u00e7as, sem orgulho, sem privil\u00e9gios&#8230;<\/p>\n<p>Ent\u00e3o est\u00e1 dito: nem religi\u00e3o, nem pol\u00edtica, nem ast\u00facia pessoal. O que nos levar\u00e1 ao c\u00e9u, ao confronto de nossas mis\u00e9rias com a abund\u00e2ncia da casa paterna, \u00e9 a pr\u00e1tica das virtudes que a f\u00e9 nos exige. Fa\u00e7a delas a fonte de energias das quais necessita, para n\u00e3o reclamar um dia que algu\u00e9m lhe roubou seu queijo&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 J\u00e1 vai longe o tempo em que a sociedade sabia dar valor \u00e0s pequenas virtudes. N\u00e3o que essas inexistam no campo pessoal dos que buscam uma vida agrad\u00e1vel. Sen\u00e3o aos olhos dos homens, ao menos aos olhos de Deus elas s\u00e3o preciosas Para muitos, virtudes s\u00e3o caretices, inven\u00e7\u00e3o de beatos. N\u00e3o combina com a [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":32776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-52220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/52220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=52220"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/52220\/revisions"}],"predecessor-version":[{"id":52221,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/52220\/revisions\/52221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/32776"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=52220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=52220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=52220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}