{"id":51010,"date":"2019-07-11T08:55:05","date_gmt":"2019-07-11T11:55:05","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=51010"},"modified":"2019-07-11T08:55:05","modified_gmt":"2019-07-11T11:55:05","slug":"como-fazer-as-pazes-com-os-erros-do-passado-licoes-de-uma-glamorosa-atriz-francesa","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/como-fazer-as-pazes-com-os-erros-do-passado-licoes-de-uma-glamorosa-atriz-francesa\/","title":{"rendered":"Como fazer as pazes com os erros do passado: li\u00e7\u00f5es de uma glamorosa atriz francesa"},"content":{"rendered":"<div class=\"io-div\" data-io-article-url=\"https:\/\/pt.aleteia.org\/2019\/07\/10\/como-fazer-as-pazes-com-os-erros-do-passado-licoes-de-uma-glamorosa-atriz-francesa\/\">\n<h2 class=\"subtitle\">Uma das mulheres mais famosas do seu tempo, Eve Lavalliere disse ter aprendido o segredo para viver bem<\/h2>\n<div class=\"base-post-content\">As apar\u00eancias enganam. Eu sei porque, como padre, frequentemente falo com pessoas que est\u00e3o buscando conselhos ou sentindo a necessidade de aliviar sua consci\u00eancia sobre isso. Por tr\u00e1s determinada imagem que se quer transmitir, h\u00e1 uma vida real diferente.Isso me traz \u00e0 mente uma hist\u00f3ria fascinante que li recentemente sobre uma mulher que parecia ter tudo. O nome dela era Eve Lavalliere, e no in\u00edcio do s\u00e9culo 20 ela era uma das mulheres mais famosas da Fran\u00e7a.<\/p>\n<p>Ela era atriz de teatro, bonita, popular, talentosa e rica. A grande atriz Sarah Bernhardt ficou maravilhada com Eve, dizendo a ela: \u201cO que voc\u00ea faz \u00e9 inato: voc\u00ea cria \u2013 voc\u00ea n\u00e3o copia os personagens. \u00c9 algo muito bonito.\u201d Eve estava no topo do mundo. Era uma das mulheres mais invejadas de seu tempo. Em 1916, quando ela se curvou depois de um show em Londres, a plateia se levantou e a aplaudiu muito. Logo em seguida, ela saiu do palco e caminhou at\u00e9 o rio T\u00e2misa, pretendendo se afogar.<\/p>\n<p>Por baixo do glamour e do sucesso, Eve era um vulc\u00e3o de m\u00e1goas do passado e erros prontos para explodir. Mais tarde, ela disse que seu estilo de vida era como navegar \u201cno vasto mar de pecados\u201d. Ela tinha tudo, mas havia perdido a paz. \u201cEu tinha tudo o que o mundo poderia oferecer, tudo que poderia desejar\u201d, ela disse, \u201cno entanto, eu me considerava a mais infeliz das almas\u201d.<\/p>\n<p>Eve Lavalliere era apenas seu nome art\u00edstico. Ela o tirara de uma mulher chamada Duchesse de la Valli\u00e8re, amante do rei Lu\u00eds XIV. Seu nome verdadeiro era Eugenie Marie Fenoglio. Ela nasceu em uma fam\u00edlia rompida, tendo um pai violento e alco\u00f3latra. Quando sua m\u00e3e finalmente encontrou coragem para deix\u00e1-lo, ele ficou furioso e a matou antes de tamb\u00e9m se matar. Eugenie ficou deprimida e com tend\u00eancias suicidas. Mesmo quando ela se transformou em Eve e encontrou grande sucesso no teatro, seu passado a assombrava. Em uma tentativa de compensar os traumas, ela teve casos com v\u00e1rios homens e esbanjou dinheiro. Nada disso trouxe-lhe felicidade, mas apenas agravou sua mis\u00e9ria. Nesse meio tempo, ela se tornou m\u00e3e solteira. Sua filha, quando adulta, ficou viciada em coca\u00edna e acabou viciando secretamente Eve para que pudesse roub\u00e1-la livremente.<\/p>\n<p>Tendo atingido as profundezas da depress\u00e3o suicida, Eve encontrou um padre que a convenceu a ir \u00e0 missa. Logo sua vida mudou. Ela deixou sua carreira de atriz para tr\u00e1s, assumiu um estilo de vida mon\u00e1stico e fez frequentes viagens mission\u00e1rias \u00e0 \u00c1frica. Os \u00faltimos anos de sua vida foram marcados pela falta de sa\u00fade e, quando ela morreu, n\u00e3o era mais famosa, glamourosa nem rica, mas estava em paz. Mesmo que sua vida material tenha piorado, as apar\u00eancias enganam. Ela desaparecera do palco do mundo, mas, ao faz\u00ea-lo, recuperou sua felicidade.<\/p>\n<div class=\"nativo-inread\"><\/div>\n<div id=\"aleteia-welcome\" data-google-query-id=\"CJW288DmrOMCFYFiwQodK6cK0Q\">\n<div id=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0__container__\"><iframe id=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/64500793\/PT_DESK_ARTICLE_WELCOME_1X1_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-google-container-id=\"3\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p>Aqui est\u00e1 seu segredo para superar seu passado, a partir de uma cita\u00e7\u00e3o sobre os \u00faltimos anos de sua vida. Eve aprendeu que \u201co passado deve ser deixado no passado e n\u00e3o pode continuar a envenenar o futur\u201do. N\u00e3o importa o quanto tentemos compensar ou fingir que est\u00e1 tudo bem, n\u00e3o seremos verdadeiramente felizes at\u00e9 lidarmos com o passado. Perdoar, aceitar quem somos e seguir em frente, \u00e9 assim que nos libertamos para compreender a felicidade do momento presente e a esperan\u00e7a do futuro.<\/p>\n<p>No final, como Eva estava sofrendo de uma doen\u00e7a cr\u00f4nica, perguntaram-lhe se tinha alguma esperan\u00e7a de ser curada. Ela respondeu: \u201cNenhuma. Mas estou t\u00e3o feliz! Voc\u00ea n\u00e3o pode imaginar como \u00e9 grande a minha felicidade\u201d. Ela ent\u00e3o acrescentou: \u201cestou nas m\u00e3os de Deus. Diga aos meus amigos dos tempos passados \u200b\u200bque voc\u00ea conheceu a pessoa mais feliz da Terra\u201d. Ela morreu em 1929, aos 63 anos.<\/p>\n<p>Somos corajosos o suficiente para deixar o passado para tr\u00e1s? Deixar tudo o que nos impede de buscar a felicidade?<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma das mulheres mais famosas do seu tempo, Eve Lavalliere disse ter aprendido o segredo para viver bem As apar\u00eancias enganam. Eu sei porque, como padre, frequentemente falo com pessoas que est\u00e3o buscando conselhos ou sentindo a necessidade de aliviar sua consci\u00eancia sobre isso. Por tr\u00e1s determinada imagem que se quer transmitir, h\u00e1 uma vida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-51010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/51010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=51010"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/51010\/revisions"}],"predecessor-version":[{"id":51012,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/51010\/revisions\/51012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/51011"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=51010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=51010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=51010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}