{"id":49777,"date":"2019-05-31T09:34:23","date_gmt":"2019-05-31T12:34:23","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=49777"},"modified":"2019-05-31T09:34:23","modified_gmt":"2019-05-31T12:34:23","slug":"regional-sul-3-da-cnbb-realiza-entre-os-dias-de-3-a-7-de-junho-assembleia-anual-em-sao-leopoldo-rs","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/regional-sul-3-da-cnbb-realiza-entre-os-dias-de-3-a-7-de-junho-assembleia-anual-em-sao-leopoldo-rs\/","title":{"rendered":"Regional Sul 3 da CNBB realiza, entre os dias de 3 a 7 de junho, assembleia anual em S\u00e3o Leopoldo (RS)"},"content":{"rendered":"<p>Entre os dias de 3 a 7 de junho, em S\u00e3o Leopoldo (RS), o Regional Sul 3 da CNBB realiza uma semana de encontros. Bispos, provinciais das congrega\u00e7\u00f5es religiosas, coordenadores de pastoral, vig\u00e1rios gerais e representantes das pastorais do Estado v\u00e3o celebrar, refletir, planejar e avaliar o que vem sendo realizado pela Igreja no Rio Grande do Sul.<\/p>\n<p>A mat\u00e9ria completa pode ser acessada <strong><a href=\"http:\/\/cnbbsul3.org.br\/regional-sul-3-da-cnbb-realiza-assembleia-anual-em-sao-leopoldo\/\">aqui<\/a> no Site do Regional Sul 3 da CNBB<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias de 3 a 7 de junho, em S\u00e3o Leopoldo (RS), o Regional Sul 3 da CNBB realiza uma semana de encontros. Bispos, provinciais das congrega\u00e7\u00f5es religiosas, coordenadores de pastoral, vig\u00e1rios gerais e representantes das pastorais do Estado v\u00e3o celebrar, refletir, planejar e avaliar o que vem sendo realizado pela Igreja no Rio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-49777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cnbb"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/49777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=49777"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/49777\/revisions"}],"predecessor-version":[{"id":49779,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/49777\/revisions\/49779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/49778"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=49777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=49777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=49777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}