{"id":47253,"date":"2019-02-23T09:47:10","date_gmt":"2019-02-23T12:47:10","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=47253"},"modified":"2019-02-25T09:48:59","modified_gmt":"2019-02-25T12:48:59","slug":"amai-os-inimigos","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/amai-os-inimigos\/","title":{"rendered":"Amai os inimigos"},"content":{"rendered":"<p>Na semana que findou tivemos a primeira turma de retiros do clero de nossa arquidiocese. Agrade\u00e7o a todos que nos acompanharam na semana que termina em que eu participei do Retiro do Clero, com uma parcela de nosso presbit\u00e9rio, na Casa de Retiros do Sumar\u00e9.<\/p>\n<p>Neste domingo estamos celebrando o s\u00e9timo do tempo comum. Estamos chegando ao final deste tempo que vai do Natal at\u00e9 a Quaresma. A liturgia deste domingo, nos apresenta por meio das suas leituras um desafio que caracteriza a vida crist\u00e3: amar o inimigo. Cristo nos desafia a passar pelo mundo fazendo o bem, testemunhando nossa perten\u00e7a a Ele por meio da viv\u00eancia da gratuidade do amor que se expressa em gestos de perd\u00e3o e de reconcilia\u00e7\u00e3o. As tr\u00eas leituras nos mostram que n\u00e3o vivemos isolados, numa redoma de vidro. Dia ap\u00f3s dia, uma grande rede de relacionamentos \u00e9 constru\u00edda por cada um de n\u00f3s. Consequentemente, a cada dia \u00e9 preciso responder aos desafios propostos pelos encontros e desencontros: fazer o bem ou o mal?<\/p>\n<p>A primeira leitura (cf. 1Sm 26,2.7-9.12-13.22-23) nos apresenta um pouco sobre alguns aspectos da vida de Davi. Davi, tendo a possibilidade de se vingar fazendo o mal, e, no entanto fez o bem. Os profetas, posteriormente, escrever\u00e3o: \u201cdeixem de fazer o mal e aprendam a fazer o bem\u201d. Saul e Davi vivem uma situa\u00e7\u00e3o emblem\u00e1tica. A morte e a vida se encontram nas m\u00e3os deles, e cabe exatamente a eles decidir se um ou outro deve viver. O texto da primeira leitura \u00e9 uma constru\u00e7\u00e3o textual pr\u00f3-Davi; ou seja, o autor procura construir um relato que contraponha dois sujeitos e suas qualidades no exerc\u00edcio da realeza. Na contraposi\u00e7\u00e3o e compara\u00e7\u00e3o, o texto deseja informar que Davi \u00e9 muito superior a Saul e, por isso, o cetro real dever\u00e1 pertencer a ele.<\/p>\n<p>O Salmo 102\/103 nos ajuda a responder rezando \u00e0 Palavra pois nos apresenta um dos maiores adjetivos que define a qualidade de Deus: bondade, ou seja, Deus \u00e9 bom. O Senhor \u00e9 bondoso e compassivo. Al\u00e9m de ser bom para com toda a humanidade, Deus ainda tem compaix\u00e3o de todos n\u00f3s. Tanto que sente compaix\u00e3o do ser humano que envia o seu pr\u00f3prio Filho. O Salmo tamb\u00e9m fala da tamanha miseric\u00f3rdia de Deus por todos n\u00f3s.<\/p>\n<p>Na Segunda leitura (cf. 1Cor 15, 45-49) S\u00e3o Paulo estabelece um paralelo entre Ad\u00e3o e Cristo a fim de salientar e explicar a grandiosidade de Cristo. Se o primeiro homem, Ad\u00e3o, foi feito alma vivente, o \u00faltimo Ad\u00e3o se tornou esp\u00edrito que d\u00e1 vida (cf. v. 45). A contraposi\u00e7\u00e3o est\u00e1 estabelecida e n\u00e3o deixa lugar a nenhuma d\u00favida. No G\u00eanesis, o primeiro Ad\u00e3o, ou seja, aquele que nascera do p\u00f3 da terra, recebeu de Deus um princ\u00edpio de vida. Cristo, por\u00e9m, de forma diferente e potencialmente maior, recebeu o pneuma imperec\u00edvel, isto \u00e9, que nunca morre. Assim, se o primeiro Ad\u00e3o est\u00e1 destinado \u00e0 morte, o \u00faltimo Ad\u00e3o se tornou o verdadeiro princ\u00edpio capaz de conferir essa vida a toda a cria\u00e7\u00e3o. E n\u00f3s que somos renascidos em Cristo somos chamados a testemunhar as consequ\u00eancias de t\u00ea-Lo encontrado.<\/p>\n<p>Para S\u00e3o Paulo, fala que em Cristo e por causa de Cristo que se inicia a nova cria\u00e7\u00e3o. Inicia-se a nova humanidade, que traz a marca da ressurrei\u00e7\u00e3o de Cristo. \u00c9 precisamente a ressurrei\u00e7\u00e3o que, de fato, reumaniza o ser humano e o faz viver para Deus em Cristo. A nova humanidade significa que todas as coisas se fazem novas; dessa forma, a novidade de vida do novo humano se exprime, principalmente, em sua forma de se relacionar. Isso aparece com muita clareza no Evangelho.<\/p>\n<p>No Evangelho (cf. <strong>Lc 6,27-38)<\/strong> deste domingo Jesus \u00e9 claro: \u201ca v\u00f3s que me escutais, eu digo: amai os vossos inimigos e fazei o bem aos que vos odeiam, bendizei os que vos amaldi\u00e7oam e rezai por aqueles que vos caluniam\u2026\u201d. \u00c9 a continuidade das bem-aventuran\u00e7as anunciadas no domingo passado, e Jesus nos ensina a viv\u00ea-las. Jesus n\u00e3o quer nem aprova um amor limitado, do tipo \u201cfaz de conta\u201d. Pede aos disc\u00edpulos que n\u00e3o sejam restritos no amor, mas sim incondicionais e que, por isso, fa\u00e7am o bem desinteressadamente, amando at\u00e9 \u201cos inimigos\u201d. Jesus ensina aos disc\u00edpulos e a n\u00f3s vivermos na gratuidade do amor; por essa raz\u00e3o: \u201cinimigos\u201d podem ser as oposi\u00e7\u00f5es que se recebe na oferta do bem e da verdade do Reino. O Senhor concede sua miseric\u00f3rdia para cada um de n\u00f3s e para a Comunidade, at\u00e9 alcan\u00e7armos o mais alto grau no amor. A\u00ed est\u00e1 nossa santifica\u00e7\u00e3o. Jesus vai nos indicando tantas situa\u00e7\u00f5es reais de nossa vida em que devemos estar alerta, para nossa santifica\u00e7\u00e3o.<\/p>\n<p>Contudo, o grande desafio lan\u00e7ado pelas leituras \u00e9 nos transformarmos no que Cristo \u00e9. O padr\u00e3o de constru\u00e7\u00e3o do ser de cada um deve ser aquele encontrado em Jesus. Permanecer na condi\u00e7\u00e3o do primeiro Ad\u00e3o \u00e9 deixar de experimentar a nova vida em Jesus; se Ad\u00e3o representa o passado, a vida de Cristo se apresenta como o resgate do presente e a abertura para o futuro de esperan\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na semana que findou tivemos a primeira turma de retiros do clero de nossa arquidiocese. Agrade\u00e7o a todos que nos acompanharam na semana que termina em que eu participei do Retiro do Clero, com uma parcela de nosso presbit\u00e9rio, na Casa de Retiros do Sumar\u00e9. Neste domingo estamos celebrando o s\u00e9timo do tempo comum. Estamos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":32777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-47253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/47253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=47253"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/47253\/revisions"}],"predecessor-version":[{"id":47254,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/47253\/revisions\/47254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/32777"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=47253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=47253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=47253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}