{"id":4366,"date":"2014-03-13T14:02:51","date_gmt":"2014-03-13T17:02:51","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/ir-luiza-recebe-medalha-sarah-kubitschek-homenagem-da-camara-de-valinhos-sera-entregue-em-reconhecimento-pelo-trabalho-social-e-voluntario-realizado\/"},"modified":"2017-04-04T15:24:46","modified_gmt":"2017-04-04T18:24:46","slug":"ir-luiza-recebe-medalha-sarah-kubitschek-homenagem-da-camara-de-valinhos-sera-entregue-em-reconhecimento-pelo-trabalho-social-e-voluntario-realizado","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/ir-luiza-recebe-medalha-sarah-kubitschek-homenagem-da-camara-de-valinhos-sera-entregue-em-reconhecimento-pelo-trabalho-social-e-voluntario-realizado\/","title":{"rendered":"Ir. Luiza recebe Medalha Sarah Kubitschek"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/catolicanet.com.br\/images\/stories\/irluiza.png\" border=\"0\" align=\"left\" \/>Homenagem da C\u00e2mara de Valinhos ser\u00e1 entregue em reconhecimento pelo trabalho social e volunt\u00e1rio realizado.<\/p>\n<p>A Ir. Luiza, da Associa\u00e7\u00e3o do Senhor Jesus (ASJ), recebe no pr\u00f3ximo dia 14, \u00e0s 19h00, da C\u00e2mara Municipal de Valinhos SP, a Medalha Sarah Kubitschek, em honra a vida dedicada ao servi\u00e7o volunt\u00e1rio e social. A medalha ser\u00e1 entregue, ainda, para a m\u00e9dica M\u00e1rcia Franzese (Grupo Rosa e Amor) e para a jornalista M\u00e1rcia Duarte (Jornal Terceira Vis\u00e3o).<br \/>Durante a sess\u00e3o solene, tamb\u00e9m haver\u00e1 a palestra: \u201cMulher na Sociedade Contempor\u00e2nea: Viv\u00eancias e Desafios\u201d, com Maria Isabel da Cruz. O evento ser\u00e1 aberto ao p\u00fablico, e o endere\u00e7o \u00e9: Rua Jos\u00e9 Milani, n\u00famero 15, Valinhos SP.<br \/>Ir. Luiza: uma vida dedicada \u00e0 evangeliza\u00e7\u00e3o<br \/>Joventina Tecilla, conhecida como Irm\u00e3 Luiza, \u00e9 presidente da Associa\u00e7\u00e3o do Senhor Jesus. Pertence \u00e0 Congrega\u00e7\u00e3o das Irm\u00e3s de S\u00e3o Jos\u00e9 de Chamb\u00e9ry, desde os 17 anos, e sempre se dedicou ao carisma da congrega\u00e7\u00e3o: cuidar dos pobres, asilos, orfanatos e col\u00e9gios femininos. Dedicou sua vida \u00e0 religiosidade com a voca\u00e7\u00e3o para evangelizar e levar a palavra de Deus para v\u00e1rias partes do pa\u00eds. <br \/>Junto do padre Eduardo Dougherty,sj, \u00e9 uma das pioneiras do movimento da Renova\u00e7\u00e3o Carism\u00e1tica no Brasil e uma das fundadoras da Associa\u00e7\u00e3o do Senhor Jesus e da Rede S\u00e9culo 21, instalada h\u00e1 mais de 30 anos em Valinhos SP.<br \/>Com mais de 50 anos de vida religiosa, Irm\u00e3 Luiza leva diariamente sua palavra a milhares de pessoas por meio dos programas da TV dos quais participa. Incans\u00e1vel, ela atende mun\u00edcipes, responde cartas e mobiliza quem est\u00e1 por perto para ajudar a quem precisa, sejam elas fam\u00edlias carentes ou institui\u00e7\u00f5es solid\u00e1rias.<br \/>Medalha Sarah Kubitschek<br \/>A Medalha Sarah Kubitschek, institu\u00edda pelo decreto legislativo 01\/2009, de autoria da ex- vereadora Dalva Berto, tem por objetivo homenagear mulheres e institui\u00e7\u00f5es que se destacam na luta pelos seus direitos e nos mais variados trabalhos sociais, e que, com desprendimento, abra\u00e7am causas na cidade e pelo seu destaque, tornam-se personalidades, muitas vezes an\u00f4nimas, mas que merecem um olhar diferenciado pelo trabalho que desenvolvem de total dedica\u00e7\u00e3o \u00e0 in\u00fameras causas sociais.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: center;\"><strong>Assessoria de Imprensa<br \/>Fabiano Fachini \u2013 MTB: 57.446<br \/>E-mail: imprensa@rs21.com.br<br \/>Tel: (19) 3849.9295<br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homenagem da C\u00e2mara de Valinhos ser\u00e1 entregue em reconhecimento pelo trabalho social e volunt\u00e1rio realizado. A Ir. Luiza, da Associa\u00e7\u00e3o do Senhor Jesus (ASJ), recebe no pr\u00f3ximo dia 14, \u00e0s 19h00, da C\u00e2mara Municipal de Valinhos SP, a Medalha Sarah Kubitschek, em honra a vida dedicada ao servi\u00e7o volunt\u00e1rio e social. A medalha ser\u00e1 entregue, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4366","post","type-post","status-publish","format-standard","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/4366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=4366"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/4366\/revisions"}],"predecessor-version":[{"id":9143,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/4366\/revisions\/9143"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=4366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=4366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=4366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}