{"id":38562,"date":"2018-02-27T16:50:27","date_gmt":"2018-02-27T19:50:27","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=38562"},"modified":"2018-02-27T16:50:27","modified_gmt":"2018-02-27T19:50:27","slug":"como-lidar-com-pessoas-dificeis-no-trabalho","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/como-lidar-com-pessoas-dificeis-no-trabalho\/","title":{"rendered":"Como lidar com pessoas dif\u00edceis no trabalho?"},"content":{"rendered":"<h2 class=\"subtitle\">Aprenda a conviver com aquelas pessoas que fazem da sua vida profissional um verdadeiro inferno<\/h2>\n<p>Pessoas t\u00f3xicas, gente amarga, misantropos\u2026 Particularmente, n\u00e3o sou a favor dessas e tantas outras etiquetas. Prefiro cham\u00e1-las de pessoas com atitudes dif\u00edceis ou feridas, j\u00e1 que \u00e9 isso que as leva a ter um tipo de comportamento n\u00e3o t\u00e3o agrad\u00e1vel.<\/p>\n<p>Sejamos realistas, ningu\u00e9m \u2013 por pior que seja a pessoa \u2013 acorda pensando: \u201choje serei feliz sendo um amargo, deixando a vida dif\u00edcil para os outros\u201d.<\/p>\n<p>Por isso, \u00e9 importante entender o que se passa na vida de quem tem um comportamento azedo. Por traz de cada rosto que n\u00e3o sorri pode haver uma hist\u00f3ria de dor, car\u00eancia ou uma marca de abandono.<\/p>\n<p>Ent\u00e3o, longe de julgarmos, precisamos olhar com compaix\u00e3o.<\/p>\n<p>Este tipo de gente est\u00e1 por toda a parte; n\u00e3o \u00e9 s\u00f3 no ambiente profissional. Algumas vezes, voc\u00ea e eu tamb\u00e9m agimos como pessoas dif\u00edceis.<\/p>\n<p><strong>A arte da simpatia<\/strong><\/p>\n<p>Como lutar contra essas pessoas que querem deixar a nossa vida mais dif\u00edcil no trabalho? Bem dizia S\u00e3o Paulo que \u00e9 preciso afundar o mal com abund\u00e2ncia de bem.<\/p>\n<p>Portanto, nossa primeira arma \u00e9 o sorriso. Pode parecer besteira, mas um sorriso desarma qualquer um.<\/p>\n<p>Talvez voc\u00ea seja o \u00fanico a dar esse presente a uma pessoa dif\u00edcil. Sua express\u00e3o poder\u00e1 ser um b\u00e1lsamo para um cora\u00e7\u00e3o que passa por um momento traum\u00e1tico. Com um sorriso, queremos dizer o seguinte: \u201co que eu posso fazer para aliviar a sua carga? Conte comigo\u201d.<\/p>\n<p>Por outro lado, lembre-se que os maus tratos s\u00e3o como qualquer presente: voc\u00ea escolhe se o aceita ou n\u00e3o. \u00c9 verdade, \u00e9 horr\u00edvel chegar ao trabalho e logo se sentir em um ambiente hostil.<\/p>\n<p>Portanto, al\u00e9m de contar com a sua arma mais poderosa \u2013 seu sorriso \u2013 voc\u00ea pode adotar estes conselhos na hora de se relacionar com pessoas dif\u00edceis e mal humoradas:<\/p>\n<ul>\n<li>Tente compreender a pessoa. Se voc\u00ea vir que n\u00e3o h\u00e1 uma resposta positiva, dedique a ela o m\u00ednimo de tempo poss\u00edvel e dirija-lhe a palavra apenas se necess\u00e1rio;<\/li>\n<li>Quando voc\u00eas conversarem, centralize o assunto na pessoa, n\u00e3o em voc\u00ea. Assim, voc\u00ea evitar\u00e1 que ela distor\u00e7a suas palavras ou manipule a informa\u00e7\u00e3o;<\/li>\n<li>Trate-a da mesma forma como voc\u00ea gostaria de ser tratado;<\/li>\n<li>Tome cuidado com o que voc\u00ea vai dizer, pois essas pessoas costumam se sentir atacadas ou ofendidas do nada. Sim, eu sei que \u00e9 desgastante tomar todos esses cuidados. Mas, lembre-se: voc\u00ea est\u00e1 falando com algu\u00e9m que est\u00e1 ferido;<\/li>\n<li>Procure n\u00e3o levar as coisas para o lado pessoal, nem mesmo os ataques diretos a voc\u00ea;<\/li>\n<li>Fale de forma clara, concisa e sem rodeios. N\u00e3o queira que a pessoa entenda o seu ponto de vista, pois ela n\u00e3o entender\u00e1;<\/li>\n<li>N\u00e3o compartilhe assuntos pessoais. Por causa de suas pr\u00f3prias feridas emocionais, essas pessoas geralmente s\u00e3o pouco prudentes quanto \u00e0 vida pessoal dos outros;<\/li>\n<li>Deixe as regras do jogo bem claras. Diga que voc\u00ea a respeita e exija respeito. Antes de tudo, siga as pol\u00edticas e procedimentos da empresa.<\/li>\n<\/ul>\n<p>Por \u00faltimo, a pergunta de um milh\u00e3o: por que uma atitude amarga de outrem est\u00e1 te tirando a paz? O que voc\u00ea poderia mudar em voc\u00ea mesmo para que este tipo de atitude n\u00e3o te impacte tanto?<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Aleteia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprenda a conviver com aquelas pessoas que fazem da sua vida profissional um verdadeiro inferno Pessoas t\u00f3xicas, gente amarga, misantropos\u2026 Particularmente, n\u00e3o sou a favor dessas e tantas outras etiquetas. Prefiro cham\u00e1-las de pessoas com atitudes dif\u00edceis ou feridas, j\u00e1 que \u00e9 isso que as leva a ter um tipo de comportamento n\u00e3o t\u00e3o agrad\u00e1vel. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/38562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=38562"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/38562\/revisions"}],"predecessor-version":[{"id":38564,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/38562\/revisions\/38564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/38563"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=38562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=38562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=38562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}