{"id":37259,"date":"2017-12-22T08:50:12","date_gmt":"2017-12-22T10:50:12","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=37259"},"modified":"2018-01-30T13:30:14","modified_gmt":"2018-01-30T15:30:14","slug":"o-natal-nos-lembra-uma-verdade-deus-nao-nos-deixa-sozinhos-escreve-dom-odilo-scherer","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/o-natal-nos-lembra-uma-verdade-deus-nao-nos-deixa-sozinhos-escreve-dom-odilo-scherer\/","title":{"rendered":"O Natal nos lembra uma verdade: \u201cDeus n\u00e3o nos deixa sozinhos\u201d, escreve dom Odilo Scherer"},"content":{"rendered":"<p>Em artigo, o arcebispo de S\u00e3o Paulo, cardeal Odilo Pedro Scherer afirma que a festa do Natal e a liturgia do tempo de Advento nos chamam \u00e0 intensa alegria. Por isso, refor\u00e7a o religioso, a prepara\u00e7\u00e3o para este tempo deve ser marcada pelo testemunho da alegria, da bondade, da esperan\u00e7a e da paz. Confira abaixo, a \u00edntegra do artigo:<br \/>\nAlegrai-vos sempre no Senhor!<\/p>\n<p>Aproxima-se a festa do Natal de Jesus e a Liturgia do Advento nos chama \u00e0 intensa alegria. \u201cAlegrai-vos sempre no Senhor. Repito, alegrai-vos! Vossa amabilidade seja conhecida de todos!\u201d (cf. Fl 4,4-7). E o motivo da alegria \u00e9 este: \u201co Senhor est\u00e1 perto!\u201d<\/p>\n<p>O Natal nos lembra esta grande e confortadora verdade: Deus n\u00e3o nos abandona, nem nos deixa sozinhos! Ele est\u00e1 perto de n\u00f3s. O Filho de Deus, nascido da Virgem Maria para este mundo, \u00e9 \u201cEmanuel \u2013 Deus conosco\u201d. O Verbo-Palavra eterna de Deus veio habitar entre n\u00f3s e nunca mais abandonou este mundo.<\/p>\n<p>Por isso, a prepara\u00e7\u00e3o pr\u00f3xima do Natal deve ser marcada pelo testemunho da alegria, da bondade, da esperan\u00e7a e da paz. No Natal, todos se desejam a paz, a alegria e coisas boas. Esses votos n\u00e3o se referem a um mito abstrato criado pela fantasia humana. A origem desses votos \u00e9 o pr\u00f3prio Natal: justamente porque, com o nascimento de Jesus. Deus veio ao encontro de todo homem e est\u00e1 pr\u00f3ximo de todos. Esse \u00e9 o motivo da grande alegria \u201cpara todo o povo\u201d, como anunciaram os anjos no nascimento Jesus em Bel\u00e9m.<\/p>\n<p>Nesta semana de prepara\u00e7\u00e3o pr\u00f3xima para a festa do Natal, fa\u00e7amos aquilo que S\u00e3o Paulo pede: rezar e apresentar a Deus nossas s\u00faplicas e a\u00e7\u00f5es de gra\u00e7as; viver em paz com todos e n\u00e3o se deixar estressar pelas preocupa\u00e7\u00f5es, nem pelo des\u00e2nimo por causa daquilo que n\u00e3o vai bem. E n\u00e3o roubem demais nossa aten\u00e7\u00e3o os presentes, Papai-Noel e a ceia de Natal\u2026 O presente e o motivo maior da festa \u00e9 Ele, o Filho de Deus que vem nos visitar. Vamos acolh\u00ea-lo com o cora\u00e7\u00e3o cheio de f\u00e9 e alegria. E tudo o mais vai ter sentido tamb\u00e9m.<\/p>\n<p>N\u00f3s temos f\u00e9 e a gra\u00e7a de conhecer Jesus Cristo e seu \u201cEvangelho da alegria\u201d. Fa\u00e7amos o que estiver ao nosso alcance para que chegue a todos a mensagem do Natal de Jesus e da salva\u00e7\u00e3o trazida pelo Filho de Deus ao mundo.<\/p>\n<p>Cardeal Odilo Pedro Scherer<br \/>\nArcebispo Metropolitano de S\u00e3o Paulo<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: CNBB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em artigo, o arcebispo de S\u00e3o Paulo, cardeal Odilo Pedro Scherer afirma que a festa do Natal e a liturgia do tempo de Advento nos chamam \u00e0 intensa alegria. Por isso, refor\u00e7a o religioso, a prepara\u00e7\u00e3o para este tempo deve ser marcada pelo testemunho da alegria, da bondade, da esperan\u00e7a e da paz. Confira abaixo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37260,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-37259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cnbb"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/37259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=37259"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/37259\/revisions"}],"predecessor-version":[{"id":37261,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/37259\/revisions\/37261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/37260"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=37259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=37259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=37259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}