{"id":3182,"date":"2013-10-22T12:17:20","date_gmt":"2013-10-22T14:17:20","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/armas-ilegais-matam-245-mil-anualmente-no-mundo\/"},"modified":"2017-03-23T14:53:32","modified_gmt":"2017-03-23T17:53:32","slug":"armas-ilegais-matam-245-mil-anualmente-no-mundo","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/armas-ilegais-matam-245-mil-anualmente-no-mundo\/","title":{"rendered":"Armas ilegais matam 245 mil anualmente no mundo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img decoding=\"async\" src=\"http:\/\/catolicanet.com.br\/images\/stories\/arma.jpg\" border=\"0\" \/><br \/>De acordo com estudos internacionais citados pela Interpol, h\u00e1 mais de 650 milh\u00f5es de armas na posse de civis em todo o mundo<\/strong><\/p>\n<p style=\"text-align: justify;\">As armas ilegais matam anualmente 245 mil pessoas em todo o mundo, informou a Organiza\u00e7\u00e3o Internacional de Pol\u00edcia Criminal (Interpol), em sua 82\u00aa Assembleia Geral, que come\u00e7ou ontem (21) em Cartagena.<\/p>\n<p>\u201cSem contar com os mortos em guerras, a cada 75 segundos, \u00e9 assassinado pelo menos um ser humano no mundo com armas de fogo ilegais. S\u00e3o 245 mil crimes a cada 365 dias\u201d, informou um comunicado da Interpol divulgado pela pol\u00edcia colombiana.<\/p>\n<p>De acordo com estudos internacionais citados pela Interpol, h\u00e1 mais de 650 milh\u00f5es de armas na posse de civis em todo o mundo \u2013 com os Estados Unidos em primeiro lugar na lista de pa\u00edses, com mais de 270 milh\u00f5es de armas.<\/p>\n<p>A Interpol considera o uso ilegal de armas de fogo \u201cuma amea\u00e7a \u00e0 seguran\u00e7a dos cidad\u00e3os, \u00e0 paz, \u00e0 estabilidade e ao desenvolvimento de todo o planeta\u201d e, para combater esse uso, tem um quadro de refer\u00eancia com informa\u00e7\u00e3o sobre 250 mil tipos de armas.<\/p>\n<p>O tema da assembleia \u00e9 Interpol: 190 Pa\u00edses, Uma Vis\u00e3o para Um Mundo Mais Seguro. O evento, que vai at\u00e9 quinta-feira (24), re\u00fane cerca de 1,5 mil delegados que analisam quest\u00f5es como o tr\u00e1fico de droga e de armas, o terrorismo e a seguran\u00e7a nas fronteiras.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Local:\u00a0 S\u00e3o Paulo (SP)<br \/>Fonte: ALETEIA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com estudos internacionais citados pela Interpol, h\u00e1 mais de 650 milh\u00f5es de armas na posse de civis em todo o mundo As armas ilegais matam anualmente 245 mil pessoas em todo o mundo, informou a Organiza\u00e7\u00e3o Internacional de Pol\u00edcia Criminal (Interpol), em sua 82\u00aa Assembleia Geral, que come\u00e7ou ontem (21) em Cartagena. \u201cSem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3182","post","type-post","status-publish","format-standard","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/3182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=3182"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/3182\/revisions"}],"predecessor-version":[{"id":7676,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/3182\/revisions\/7676"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=3182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=3182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=3182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}