{"id":31485,"date":"2017-06-12T08:53:13","date_gmt":"2017-06-12T11:53:13","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/?p=31485"},"modified":"2017-06-13T12:00:29","modified_gmt":"2017-06-13T15:00:29","slug":"santo-antonio-o-santo-sem-fronteiras","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/santo-antonio-o-santo-sem-fronteiras\/","title":{"rendered":"Santo Ant\u00f4nio, o Santo sem Fronteiras"},"content":{"rendered":"<p style=\"text-align: justify;\">A vida deste santo t\u00e3o querido foi marcada por muitos acontecimentos que tocam a sensibilidade crist\u00e3, especialmente do povo brasileiro, sobretudo no que diz respeito ao seguimento radical de Cristo e no cumprimento da sua Santa vontade. Santo Ant\u00f4nio nasceu provavelmente no ver\u00e3o de 1195, ao lado da S\u00e9 de Lisboa; no batismo recebeu o nome de Fernando de Bulh\u00f5es. Ali cresceu e recebeu os sacramentos da inicia\u00e7\u00e3o crist\u00e3. Aos 15 anos, entrou para o Mosteiro de S\u00e3o Vicente de Fora, dos frades agostinianos, e mais tarde completou a sua educa\u00e7\u00e3o em Santa Cruz de Coimbra, tamb\u00e9m da mesma ordem. Em Portugal aprendeu da cultura cl\u00e1ssica lusitana a sua natureza curiosa, e o seu ardente desejo de aprender das sagradas escrituras o levou a estudar a sagrada teologia com tanto esmero. Talvez este profundo amor \u00e0s Sagradas Escrituras impulsionasse o jovem Ant\u00f4nio nos serm\u00f5es teol\u00f3gicos \u2013, uma obra cl\u00e1ssica e eminente que vale para todos os tempos, sempre atual em seus ensinamentos prof\u00e9ticos.<br \/>\nSanto Ant\u00f3nio de Lisboa pertence ao n\u00famero dos santos sem fronteiras. Lisboeta e Portugu\u00eas de sangue, percorreu o mundo afora ainda jovem, com o desejo de evangelizar os infi\u00e9is. Depois de conhecer o testemunho dos frades de S\u00e3o Francisco que passavam por Portugal, vindos das miss\u00f5es de Marrocos, o jovem agostiniano sentiu vir \u00e0 tona seu esp\u00edrito mission\u00e1rio e n\u00e3o hesitou em seguir o exemplo de Francisco de Assis, e se fez frade menor na ordem franciscana, colocando-se dispon\u00edvel para a prega\u00e7\u00e3o ser\u00e1fica e a vida de pobreza evang\u00e9lica. Partiu de Portugal para levar a Boa Nova de Jesus Cristo Salvador.<br \/>\nAnt\u00f4nio de Lisboa foi um pregador eloquente e incans\u00e1vel, sua vida era uma prega\u00e7\u00e3o viva, traduzida pelo modo como vivia em simplicidade e ora\u00e7\u00e3o, mas foi, sobretudo, um homem de f\u00e9 robusta, traduzida em amor \u00e0 justi\u00e7a, \u00e0 fraternidade e \u00e0 verdade do Evangelho. A sua palavra prof\u00e9tica e a sua presen\u00e7a no meio do povo por onde passava comunicava vida, e, especialmente aos pobres sem esperan\u00e7a, ele transmitia a esperan\u00e7a evang\u00e9lica.<br \/>\nViveu parte de sua vida em miss\u00e3o pelo norte da It\u00e1lia, e com apenas 26 anos de idade foi eleito Provincial dos Franciscanos do norte da It\u00e1lia, eleito em cap\u00edtulo na presen\u00e7a do pai fundador Francisco de Assis, a quem gostava de chamar-lhe de \u201cmeu bispo\u201d, mas seu desejo era pregar e rumou pelos caminhos da It\u00e1lia setentrional, praticando a caridade, catequizando o povo simples, dando assist\u00eancia espiritual aos enfermos e exclu\u00eddos e at\u00e9 mesmo organizando socialmente essas comunidades.<br \/>\nPregava contra as novas formas de corrup\u00e7\u00e3o nascidas do luxo e da avareza dos ricos e poderosos das cidades, onde se disseminaram filosofias her\u00e9ticas. Ele viajou por muitas regi\u00f5es da It\u00e1lia e, por tr\u00eas anos, andou pelo Sul da Fran\u00e7a, principal foco dessas heresias. Ant\u00f4nio viveu, sobretudo os seus \u00faltimos anos, em P\u00e1dua. A\u00ed trabalhou sem se poupar pela causa de Jesus Cristo; foi amado e respeitado pelo seu saber e pelo seu amor aos pobres. O povo chamava-lhe \u201co santo\u201d, porque Ant\u00f4nio era um espelho da ternura e do perd\u00e3o de Deus.<br \/>\nOs paduanos consideram-no o seu santo padroeiro, e os portugueses orgulham-se de ver um filho da sua p\u00e1tria \u2013 Fernando \u2013 t\u00e3o universalmente amado, mas Ant\u00f4nio \u00e9 um santo sem fronteiras, porque quem \u00e9 verdadeiramente grande supera os limites geogr\u00e1ficos e nacionais.<br \/>\nFilho de Deus e membro da Igreja, Santo Ant\u00f4nio de Lisboa \u00e9 tamb\u00e9m Santo Ant\u00f4nio de P\u00e1dua, e do Brasil, mas \u00e9, sobretudo, um santo popular e da igreja universal. No final de sua vida, Santo Ant\u00f4nio, que era portador de hidropisia maligna (doen\u00e7a que causa reten\u00e7\u00e3o de l\u00edquido no organismo, fazendo com que a pessoa fique inchada), sentiu que a hora de se encontrar com o Senhor se aproximava, desejou ir para a igreja de Santa Maria, mas estando muito debilitado parou em Arcella, que se encontra \u00e0s portas de P\u00e1dua. Aos 36 anos, na sexta-feira do dia 13 de junho de 1231, no convento de Santa Maria de Arcella, \u00e0s portas da cidade que batizou de &#8220;casa espiritual\u201d, morreu ap\u00f3s pronunciar as palavras: \u201cVideo Dominum Meum\u201d (Vejo o meu Senhor!)<br \/>\nSeu culto \u00e9 um dos mais populares, e foram tantos os milagres ocorridos que, onze meses ap\u00f3s sua morte, fora canonizado pelo Papa Greg\u00f3rio IX na cidade de Espoleto. Em 1263, quando seu corpo foi exumado, sua l\u00edngua estava intacta, e continua intacta at\u00e9 hoje numa redoma de vidro na Bas\u00edlica de Santo Ant\u00f4nio, em P\u00e1dua, onde est\u00e3o seus restos mortais.<br \/>\nMais tarde, em 1934, foi declarado Padroeiro de Portugal. E, em 1946, o Papa Pio XII proclamou Santo Ant\u00f4nio \u201cDoutor da Igreja\u201d, com o t\u00edtulo de \u201cDoutor Evang\u00e9lico\u201d. Santo Ant\u00f4nio n\u00e3o perdeu sua atualidade e \u00e9 invocado pelo povo crist\u00e3o at\u00e9 hoje. Rendemos gra\u00e7as ao Alt\u00edssimo e sumo bem pelo testemunho evang\u00e9lico e apost\u00f3lico do glorioso frei Ant\u00f4nio, Santo doutor da Igreja, ilustre irm\u00e3o da Ordem dos Frades Menores, fiel seguidor de Jesus Cristo nas pegadas do Poverello de Assis.<br \/>\nViva Santo Ant\u00f4nio, o Santo querido, que interceda junto de Deus pela conc\u00f3rdia, pela paz e pela justi\u00e7a na cidade do Rio de Janeiro!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vida deste santo t\u00e3o querido foi marcada por muitos acontecimentos que tocam a sensibilidade crist\u00e3, especialmente do povo brasileiro, sobretudo no que diz respeito ao seguimento radical de Cristo e no cumprimento da sua Santa vontade. Santo Ant\u00f4nio nasceu provavelmente no ver\u00e3o de 1195, ao lado da S\u00e9 de Lisboa; no batismo recebeu o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-31485","post","type-post","status-publish","format-standard","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/31485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=31485"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/31485\/revisions"}],"predecessor-version":[{"id":31486,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/31485\/revisions\/31486"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=31485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=31485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=31485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}