{"id":30441,"date":"2017-06-05T14:28:21","date_gmt":"2017-06-05T17:28:21","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/2017\/06\/05\/colegio-pio-brasileiro-lanca-novo-site-em-roma\/"},"modified":"2017-06-07T13:55:27","modified_gmt":"2017-06-07T16:55:27","slug":"colegio-pio-brasileiro-lanca-novo-site-em-roma","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/colegio-pio-brasileiro-lanca-novo-site-em-roma\/","title":{"rendered":"Col\u00e9gio Pio Brasileiro lan\u00e7a novo site em Roma"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.catolicanet.com.br\/images\/stories\/noticias2017\/rv26049_articolo.jpg\" border=\"0\" align=\"left\" \/>Roma (RV) &#8211; O Col\u00e9gio Pio Brasileiro, localizado em Roma, lan\u00e7ou novo site neste Domingo de Pentecostes, 04, \u00e0s 19h (hora local) nas depend\u00eancias da pr\u00f3pria sede, apresentando um formato voltado \u00e0 veicula\u00e7\u00e3o de not\u00edcias e artigos dos sacerdotes estudantes dos diversos cursos de mestrado e doutorado das Universidades Pontif\u00edcias. Entre as novidades destacam-se tamb\u00e9m a implementa\u00e7\u00e3o de redes sociais, canal no Youtube e a possibilidade de transmiss\u00e3o ao vivo de eventos atrav\u00e9s de uma WebTV.<\/p>\n<p>A R\u00e1dio Vaticano ouviu o Pe. Geraldo Maia&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/media02.radiovaticana.va\/audio\/audio2\/mp3\/00584338.mp3\">Clique aqui para ouvir:<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Com a palavra inicial, Pe. Geraldo Maia, reitor da Institui\u00e7\u00e3o, relacionando a inaugura\u00e7\u00e3o do novo site com o evento de Pentecostes, fez uma alus\u00e3o \u00e0s palavras do Papa Francisco para o Dia Mundial das Comunica\u00e7\u00f5es, onde afirma que o Esp\u00edrito Santo \u00e9 quem semeia o desejo do Reino atrav\u00e9s de muitos canais vivos, tornando as pessoas como far\u00f3is na escurid\u00e3o deste mundo e que iluminam a rota, abrindo novas sendas de confian\u00e7a e esperan\u00e7a.<\/p>\n<p>\u201cA atual p\u00e1gina \u00e9 continuidade e ruptura. Continuidade da comunica\u00e7\u00e3o de nosso Col\u00e9gio, que difunde os principais eventos de nossa comunidade presbiteral, neste itiner\u00e1rio de forma\u00e7\u00e3o permanente. \u00c9 canal de comunica\u00e7\u00e3o com tantas pessoas queridas e outras tantas desconhecidas que se aproximam de n\u00f3s, atra\u00eddas pelos grandes feitos aqui realizados. Ruptura com uma forma j\u00e1 arcaica de fazer comunica\u00e7\u00e3o. Trata-se de um site mais arrojado, com novo layout, atendendo \u00e0s demandas do atual contexto tecnol\u00f3gico e relacional\u201d, enfatizou o reitor.<\/p>\n<p>Pe. Gilvair Messias, um dos respons\u00e1veis pela remodelagem do site, apresentou o novo ve\u00edculo aos presentes, explicando o objetivo de alcan\u00e7ar um p\u00fablico espec\u00edfico: \u201cqueremos comunicar a vida do Col\u00e9gio, o que aqui tamb\u00e9m \u00e9 produzido, para os padres, bispos e leigos, com particular aten\u00e7\u00e3o \u00e0queles que s\u00e3o do nosso Brasil\u201d. O sacerdote ainda, em sua fala, exp\u00f4s como foi pensada a constitui\u00e7\u00e3o de cada parte do novo media e os conte\u00fados propostos. \u201cNa parte das fotos, por exemplo, encontramos aquelas antigas e as mais atuais; \u00e9 belo olhar o registro feito das visitas dos Papas Paulo VI e S\u00e3o Jo\u00e3o Paulo II \u00e0 nossa casa\u201d, ressaltou.<\/p>\n<p>O novo site pode ser acessado atrav\u00e9s do endere\u00e7o eletr\u00f4nico www.piobrasileiro.com e se encontra tamb\u00e9m com design responsivo para facilitar o acesso atrav\u00e9s de dispositivos m\u00f3veis como tablets e celulares. A parte t\u00e9cnica esteve a cargo da empresa Banana, Canela e Design, localizada na cidade de Po\u00e7os de Caldas, em Minas Gerais. Entre os convidados para o evento de lan\u00e7amento, esteve presente Silvonei Jos\u00e9, jornalista respons\u00e1vel pela programa\u00e7\u00e3o brasileira da R\u00e1dio Vaticano.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Fonte: R\u00e1dio Vaticano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma (RV) &#8211; O Col\u00e9gio Pio Brasileiro, localizado em Roma, lan\u00e7ou novo site neste Domingo de Pentecostes, 04, \u00e0s 19h (hora local) nas depend\u00eancias da pr\u00f3pria sede, apresentando um formato voltado \u00e0 veicula\u00e7\u00e3o de not\u00edcias e artigos dos sacerdotes estudantes dos diversos cursos de mestrado e doutorado das Universidades Pontif\u00edcias. Entre as novidades destacam-se tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-30441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/30441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=30441"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/30441\/revisions"}],"predecessor-version":[{"id":30485,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/30441\/revisions\/30485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/30440"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=30441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=30441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=30441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}