{"id":19903,"date":"2016-12-13T12:45:46","date_gmt":"2016-12-13T14:45:46","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/2016\/12\/13\/carta-do-papa-a-assad-dom-zenari-esperamos-em-uma-solucao\/"},"modified":"2017-06-02T10:02:40","modified_gmt":"2017-06-02T13:02:40","slug":"carta-do-papa-a-assad-dom-zenari-esperamos-em-uma-solucao","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/carta-do-papa-a-assad-dom-zenari-esperamos-em-uma-solucao\/","title":{"rendered":"Carta do Papa a Assad. Dom Zenari: esperamos em uma solu\u00e7\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.catolicanet.com.br\/images\/stories\/noticias\/epa2282588_articolo.jpg\" border=\"0\" align=\"left\" \/>Cidade do Vaticano (RV) &#8211; Cada vez mais complexo o cen\u00e1rio na S\u00edria onde a guerra n\u00e3o tem fim. E o Papa ap\u00f3s de domingo no Angelus, faz ouvir a sua voz novamente contra todas as formas de extremismo, para a cessa\u00e7\u00e3o das viol\u00eancias e o respeito do direito humanit\u00e1rio internacional. E o faz em uma carta enviada ao presidente s\u00edrio Assad e entregue pelo N\u00fancio Apost\u00f3lico, o cardeal Mario Zenari. Enquanto isso Aleppo permanece sob as bombas e Palmira \u00e9 assediada pelo Estado isl\u00e2mico.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/media02.radiovaticana.va\/audio\/audio2\/mp3\/00561669.mp3\">Clique aqui para ouvir:<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">O Papa confia ao N\u00fancio na S\u00edria, Dom Mario Zenari, elevado \u00e0 p\u00farpura cardinal\u00edcia precisamente em um sinal de afeto pelo amado povo s\u00edrio, uma carta ao presidente. No texto, conforme refere a Sala de Imprensa do Vaticano, um apelo a Bashar al Assad e \u00e0 comunidade internacional pelo \u201cfim da viol\u00eancia\u201d e por uma \u201csolu\u00e7\u00e3o pac\u00edfica das hostilidades\u201d. Mas tamb\u00e9m a \u201ccondena\u00e7\u00e3o de todas as formas de extremismo e terrorismo independentemente da sua origem\u201d e a exorta\u00e7\u00e3o ao presidente a \u201cgarantir que o direito humanit\u00e1rio internacional seja plenamente respeitado, com refer\u00eancia \u00e0 prote\u00e7\u00e3o de civis e o acesso \u00e0s ajudas humanit\u00e1rias\u201d. Sobre uma visita de cortesia ao presidente Assad, ap\u00f3s receber a p\u00farpura cardinal\u00edcia, eis o que disse \u00e0 R\u00e1dio Vaticano o N\u00fancio Apost\u00f3lico Cardeal Mario Zenari:<\/p>\n<p>R. &#8211; Fui recebido pelo Presidente para uma visita de cortesia, j\u00e1 que retornava como cardeal e era algo de \u00fanico, e todos entenderam isso &#8211; do governo aos cidad\u00e3os -, que era um gesto do Papa de proximidade ao sofrimento dos s\u00edrios . Por ocasi\u00e3o desta visita, com o clima desta nomea\u00e7\u00e3o, eu entreguei uma carta do Papa. N\u00e3o \u00e9 dif\u00edcil intuir o que est\u00e1 escrito nesta carta. \u00c9 claro que \u00e9 tudo o que o Papa sempre disse sobre o conflito s\u00edrio e, portanto, tamb\u00e9m um chamado de aten\u00e7\u00e3o para o aspecto humanit\u00e1rio, em primeiro lugar.<\/p>\n<p>P. \u2013 O senhor teve a impress\u00e3o de que o presidente apreciou a carta?<\/p>\n<p>R. &#8211; A impress\u00e3o que eu tive \u00e9 que recebeu esta carta do Papa &#8211; eu diria -, com muita gratid\u00e3o. Reconhecimento. Ele a leu, e apreciou muito: isso sim, eu posso dizer &#8230; (SP)<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Fonte: R\u00e1dio Vaticano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cidade do Vaticano (RV) &#8211; Cada vez mais complexo o cen\u00e1rio na S\u00edria onde a guerra n\u00e3o tem fim. E o Papa ap\u00f3s de domingo no Angelus, faz ouvir a sua voz novamente contra todas as formas de extremismo, para a cessa\u00e7\u00e3o das viol\u00eancias e o respeito do direito humanit\u00e1rio internacional. E o faz em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/19903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=19903"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/19903\/revisions"}],"predecessor-version":[{"id":27240,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/19903\/revisions\/27240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/19902"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=19903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=19903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=19903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}