{"id":17511,"date":"2016-08-31T18:45:26","date_gmt":"2016-08-31T21:45:26","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/2016\/08\/31\/simposio-inter-cristao-em-salonica-mensagem-do-papa-e-de-bartolomeu\/"},"modified":"2017-06-02T14:08:23","modified_gmt":"2017-06-02T17:08:23","slug":"simposio-inter-cristao-em-salonica-mensagem-do-papa-e-de-bartolomeu","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/simposio-inter-cristao-em-salonica-mensagem-do-papa-e-de-bartolomeu\/","title":{"rendered":"Simp\u00f3sio inter-crist\u00e3o em Sal\u00f3nica &#8211; mensagem do Papa e de Bartolomeu"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.catolicanet.com.br\/images\/stories\/papas\/ansa605779_articolo.jpg\" border=\"0\" align=\"left\" \/>Decorre de 28 a 30 deste m\u00eas em Sal\u00f3nica, na Gr\u00e9cia, o tradicional Simp\u00f3sio Intercrist\u00e3o\u00a0 dos Te\u00f3logos Ortodoxos e Cat\u00f3licos promovido pelo Instituto Franciscano de Espiritualidade da Pontif\u00edcia Universidade Antonianium de Roma e pela Faculdade Teol\u00f3gica Ortodoxa da Universidade Arist\u00f3teles de Sal\u00f3nica. O escopo \u00e9 favorecer o di\u00e1logo teol\u00f3gico e cultural entre cat\u00f3licos e ortodoxos.\u00a0 O tema deste ano \u00e9 \u201cA necessidade de uma reevangeliza\u00e7\u00e3o das comunidades crist\u00e3s na Europa\u201d.<\/p>\n<p>Na mensagem que dirigiu ao Cardeal Kurt Koch, Presidente do Conselho Pontif\u00edcio para a Promo\u00e7\u00e3o da Unidade dos Crist\u00e3os, o Papa Francisco sublinha que a presen\u00e7a na Europa de tantas pessoas que, embora baptizadas, n\u00e3o t\u00eam consci\u00eancia do dom da f\u00e9 recebida, n\u00e3o sentem a consola\u00e7\u00e3o que ela pode trazer e n\u00e3o participam plenamente da vida da comunidade crist\u00e3, representa um desafio para todas as Igrejas presentes no continente. Numa Europa onde esmorecem cada vez mais as liga\u00e7\u00f5es com as ra\u00edzes crist\u00e3s, adverte-se claramente a necessidade de uma nova obra de evangeliza\u00e7\u00e3o \u2013 escreve o Papa sublinhando que este empenho mission\u00e1rio \u00e9 sustido pela profunda convic\u00e7\u00e3o de que Cristo\u00a0 sempre pode, com a sua novidade, renovar a nossa vida e a nossa comunidade, e mesmo que atravesse \u00e9pocas obscuras e fraquezas eclesiais, a proposta crist\u00e3 n\u00e3o envelhece nunca\u201d.<\/p>\n<p>O Papa exprime o desejo de que o Simp\u00f3sio possa contribuir para encontrar novos caminhos, m\u00e9todos criativos e uma linguagem adapta para fazer chegar o an\u00fancio de Cristo em toda a sua beleza ao homem europeu contempor\u00e2neo.<\/p>\n<p>Tamb\u00e9m o Patriarca Ecum\u00e9nico de Constantin\u00f3pla , Bartolomeu,\u00a0 dirigiu uma mensagem ao Simp\u00f3sio\u00a0 em que sublinha que \u201csegundo a sapi\u00eancia dos Padres, \u201cmesmo que sejam milh\u00f5es os que escrevem os evangelhos, todos escrevem a mesma coisa, os muitos s\u00e3o um e nenhum membro da multid\u00e3o dos autores pode prejudicar o um\u201d. Mas, n\u00e3o obstante isto \u2013 prossegue \u2013 os recentes ataques terroristas em pa\u00edses da Europa Ocidental demonstram a absoluta necessidade de voltar a evangelizar o continente, porque o problema n\u00e3o reside tanto no terrorismo da parte de membros de uma particular religi\u00e3o, quanto na vasta descristianiza\u00e7\u00e3o da Europa que durante as \u00faltimas d\u00e9cadas segue o caminho de um cont\u00ednuo afastamento dos valores e das tradi\u00e7\u00f5es crist\u00e3s e est\u00e1 a adoptar novas teorias e costumes que se op\u00f5em completamente \u00e0s leis de Deus.<\/p>\n<p>A falta de favores est\u00e1veis e s\u00e3o e a liberdade desenfreada do homem que se orienta para escolhas catastr\u00f3ficas para o g\u00e9nero humano, levaram o homem ao desespero e \u00e0 procura de um apoio espiritual para poder p\u00f4r termo a esta corrida vertiginosa em direc\u00e7\u00e3o \u00e0 destrui\u00e7\u00e3o do mundo e dos valores humanos \u2013 escreve o Patriarca, segundo o qual o retorno \u00e0 f\u00e9 e \u00e0 vida crist\u00e3s, o \u00danico Evangelho de Cristo, \u00e0 Luz, \u00e0 Verdade e \u00e0 Vida, \u00e9 a \u00fanica verdadeira Vida, que pode dar respostas concretas \u00e0s preocupa\u00e7\u00f5es do homem contempor\u00e2neo.<\/p>\n<p>Bartolomeu considera por isso que na medida em que o Simp\u00f3sio se encaminhar para a evangeliza\u00e7\u00e3o e a reevangeliza\u00e7\u00e3o da Europa no s\u00e9culo XXI ser\u00e1 muito importante, porque dar\u00e1 a possibilidade que seja ouvido mais ampla e claramente\u00a0 o Evangelho que nos foi dado por Deus.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Fonte: R\u00e1dio Vaticano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decorre de 28 a 30 deste m\u00eas em Sal\u00f3nica, na Gr\u00e9cia, o tradicional Simp\u00f3sio Intercrist\u00e3o\u00a0 dos Te\u00f3logos Ortodoxos e Cat\u00f3licos promovido pelo Instituto Franciscano de Espiritualidade da Pontif\u00edcia Universidade Antonianium de Roma e pela Faculdade Teol\u00f3gica Ortodoxa da Universidade Arist\u00f3teles de Sal\u00f3nica. O escopo \u00e9 favorecer o di\u00e1logo teol\u00f3gico e cultural entre cat\u00f3licos e ortodoxos.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-17511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/17511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=17511"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/17511\/revisions"}],"predecessor-version":[{"id":28645,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/17511\/revisions\/28645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media\/17510"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=17511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=17511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=17511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}