{"id":13082,"date":"2016-01-20T13:54:09","date_gmt":"2016-01-20T15:54:09","guid":{"rendered":"http:\/\/catolicanet.net\/wp-cnet\/2016\/01\/20\/cnbb-e-caritas-lancam-campanha-em-solidariedade-a-migrantes-e-refugiados\/"},"modified":"2017-05-26T16:21:16","modified_gmt":"2017-05-26T19:21:16","slug":"cnbb-e-caritas-lancam-campanha-em-solidariedade-a-migrantes-e-refugiados","status":"publish","type":"post","link":"https:\/\/catolicanet.net\/wp-cnet\/cnbb-e-caritas-lancam-campanha-em-solidariedade-a-migrantes-e-refugiados\/","title":{"rendered":"CNBB e C\u00e1ritas lan\u00e7am campanha em solidariedade a migrantes e refugiados"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/catolicanet.com.br\/images\/stories\/geral\/cartaz refugiados.jpg\" border=\"0\" align=\"left\" \/>A coleta de solidariedade ocorrer\u00e1 por meio de dep\u00f3sito banc\u00e1rio<\/p>\n<p>A Confer\u00eancia Nacional dos Bispos do Brasil (CNBB) e a C\u00e1ritas Brasileira, em conson\u00e2ncia com o Jubileu Extraordin\u00e1ria da Miseric\u00f3rdia, convocado pelo papa Francisco, promovem Campanha de solidariedade em prol dos migrantes e refugiados. Confira o v\u00eddeo da campanha. <\/p>\n<p>\u201cEstamos diante de uma situa\u00e7\u00e3o de migra\u00e7\u00e3o muito grande. O papa tem nos alertado para sairmos ao encontro dos nossos irm\u00e3os e irm\u00e3s que deixam suas terras, que buscam aconchego e lugar para morar. Vamos ajudar com essa a\u00e7\u00e3o solid\u00e1ria promovida pela CNBB e C\u00e1ritas, para podermos melhor acolher, a Jesus, por meio dos nossos irm\u00e3os que sofrem\u201d, motiva o bispo auxiliar de Bras\u00edlia (DF) e secret\u00e1rio geral da CNBB, dom Leonardo Steiner. <\/p>\n<p>Por ocasi\u00e3o do Dia Mundial do Migrante e do Refugiado, celebrado no domingo, 17 de janeiro, o Vaticano divulgou mensagem do papa Francisco. O texto, intitulado &#8220;Os migrantes e os refugiados nos interpelam: a resposta do Evangelho da miseric\u00f3rdia\u201d, recorda os sofrimentos dos povos que s\u00e3o obrigados a deixar as regi\u00f5es onde habitam. <\/p>\n<p>Na mensagem, o papa pede que a sociedade se empenha para minimizar os sofrimentos dessas popula\u00e7\u00f5es. \u201cOs emigrantes s\u00e3o nossos irm\u00e3os e irm\u00e3s que procuram uma vida melhor longe da pobreza, da fome, da explora\u00e7\u00e3o e da injusta distribui\u00e7\u00e3o dos recursos do planeta, que deveriam ser divididos equitativamente entre todos. Porventura n\u00e3o \u00e9 desejo de cada um melhorar as pr\u00f3prias condi\u00e7\u00f5es de vida e obter um honesto e leg\u00edtimo bem-estar que possa partilhar com os seus entes queridos?\u201d, refletiu Francisco. <\/p>\n<p>Ao final do texto, o papa envia palavras de esperan\u00e7a aos migrantes e refugiados: \u201cQueridos irm\u00e3os e irm\u00e3s emigrantes e refugiados! Na raiz do Evangelho da miseric\u00f3rdia, o encontro e a recep\u00e7\u00e3o do outro entrela\u00e7am-se com o encontro e a recep\u00e7\u00e3o de Deus: acolher o outro \u00e9 acolher a Deus em pessoa! N\u00e3o deixeis que vos roubem a esperan\u00e7a e a alegria de viver que brotam da experi\u00eancia da miseric\u00f3rdia de Deus, que se manifesta nas pessoas que encontrais ao longo dos vossos caminhos!\u201d, escreveu. <\/p>\n<p>Realidade pelo mundo<\/p>\n<p>Em todo o planeta, 60 milh\u00f5es de pessoas foram for\u00e7adas a deixar suas casas, migrando para outros pa\u00edses. Atualmente, constata-se uma crescente discrimina\u00e7\u00e3o e criminaliza\u00e7\u00e3o das pessoas que se encontram na condi\u00e7\u00e3o de migrantes e refugiadas. Essa situa\u00e7\u00e3o contribui para que essas popula\u00e7\u00f5es se tornem ainda mais vulner\u00e1veis em termos socioecon\u00f4micos e mais sujeitas \u00e0 viol\u00eancia.<\/p>\n<p>Os recursos arrecadados com a campanha ser\u00e3o destinados a a\u00e7\u00f5es de sensibiliza\u00e7\u00e3o da sociedade quanto \u00e0 import\u00e2ncia da acolhida, solidariedade e ajuda humanit\u00e1ria a essas pessoas. S\u00e3o atividades voltadas ao fortalecimento das iniciativas j\u00e1 existentes; de apoio \u00e0 cria\u00e7\u00e3o de novos centros de acolhida, atendimento e promo\u00e7\u00e3o dos direitos humanos.<\/p>\n<p>Al\u00e9m disso, por meio dos recursos pretende-se criar uma rede cat\u00f3lica destinada a formar, integrar e fomentar o acolhimento, a prote\u00e7\u00e3o legal e a integra\u00e7\u00e3o local de migrantes e refugiados em todo o Brasil; e de apoio a iniciativas correlatas desenvolvidas em outros pa\u00edses, com a a\u00e7\u00e3o da Caritas Internacional.<\/p>\n<p>A coleta de solidariedade deve ser feita por meio de dep\u00f3sito banc\u00e1rio, na conta da C\u00e1ritas. <\/p>\n<p>Banco do Brasil<\/p>\n<p>Ag\u00eancia: 3475-4<\/p>\n<p>Conta corrente: 32.792-1<\/p>\n<p>Caixa Econ\u00f4mica Federal<\/p>\n<p>Ag\u00eancia: 1041<\/p>\n<p>Opera\u00e7\u00e3o: 003<\/p>\n<p>Conta Corrente: 3735-5<\/p>\n<p>Baixe os materiais da campanha e ajude a divulgar: http:\/\/caritas.org.br\/refugiados-e-imigrantes <br \/>\u00daltimas not\u00edcias<\/p>\n<p> A educa\u00e7\u00e3o dos filhos<br \/> As obras de miseric\u00f3rdia espirituais<br \/> Interroga\u00e7\u00f5es de 2016<br \/> CNBB e C\u00e1ritas lan\u00e7am campanha em solidariedade a migrantes e refugiados<br \/> Perten\u00e7a<\/p>\n<p>Artigos dos Bispos<\/p>\n<p> A educa\u00e7\u00e3o dos filhos<br \/> As obras de miseric\u00f3rdia espirituais<br \/> Interroga\u00e7\u00f5es de 2016<br \/> Perten\u00e7a<br \/> S\u00e3o Sebasti\u00e3o<br \/> Elogios \u00e0 Maria, M\u00e3e de Deus<br \/> A dignidade do trabalho<\/p>\n<p>Fonte: CNBB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A coleta de solidariedade ocorrer\u00e1 por meio de dep\u00f3sito banc\u00e1rio A Confer\u00eancia Nacional dos Bispos do Brasil (CNBB) e a C\u00e1ritas Brasileira, em conson\u00e2ncia com o Jubileu Extraordin\u00e1ria da Miseric\u00f3rdia, convocado pelo papa Francisco, promovem Campanha de solidariedade em prol dos migrantes e refugiados. Confira o v\u00eddeo da campanha. \u201cEstamos diante de uma situa\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-13082","post","type-post","status-publish","format-standard","hentry","category-cnbb"],"_links":{"self":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/13082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/comments?post=13082"}],"version-history":[{"count":1,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/13082\/revisions"}],"predecessor-version":[{"id":23920,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/posts\/13082\/revisions\/23920"}],"wp:attachment":[{"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/media?parent=13082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/categories?post=13082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicanet.net\/wp-cnet\/wp-json\/wp\/v2\/tags?post=13082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}